{"id":10491,"date":"2024-02-23T13:09:06","date_gmt":"2024-02-23T20:09:06","guid":{"rendered":"https:\/\/periodicorealidades.com\/?p=10491"},"modified":"2024-02-23T13:09:07","modified_gmt":"2024-02-23T20:09:07","slug":"aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia","status":"publish","type":"post","link":"https:\/\/periodicorealidades.com\/index.php\/2024\/02\/23\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\/","title":{"rendered":"Aseguran 60 Kilos de Coca\u00edna Ocultos en Contenedor en Zapopan; Proven\u00eda de Bolivia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Elementos de la FGR decomisaron 60 paquetes de coca\u00edna ocultos en un contenedor proveniente de Bolivia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Autoridades de&nbsp;<strong>Zapopan, Jalisco,<\/strong>&nbsp;aseguraron un contenedor con casi 60 kilos de coca\u00edna en el interior de un contenedor, procedente de Bolivia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un comunicado, la<strong>\u00a0Fiscal\u00eda General de la Rep\u00fablica<\/strong>\u00a0inform\u00f3 que se integra una carpeta de investigaci\u00f3n contra quienes resulten responsables de este hallazgo.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/static-live.nmas.com.mx\/nmas-news\/styles\/large\/cloud-storage\/2024-02\/cocaina-zapopan.jpg.webp?itok=_1UooDPu\" alt=\"Hallazgo cocaina en Zapopan\"\/><figcaption class=\"wp-element-caption\">El contenedor en el que ven\u00eda la droga proven\u00eda de Bolivia. Foto: FGR<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, se\u00f1al\u00f3 que elementos de la polic\u00eda federal ministerial de la\u00a0<strong>Agencia de Investigaci\u00f3n Criminal<\/strong>\u00a0recibieron una denuncia por parte del apoderado legal de una cadena comercial, ubicada en la avenida Vallarta de dicho municipio en el que se informaba que en una bodega se encontraban diversos paquetes con droga en un contenedor de mercanc\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Autoridades se trasladaron hasta dicho lugar e inspeccionaron la bodega y el contenedor, en el que hallaron<strong>&nbsp;60 paquetes con 59 kilos 969 gramos de coca\u00edna.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo asegurado fue puesto a disposici\u00f3n del Ministerio P\u00fablico Federal, quien contin\u00faa con la integraci\u00f3n de la carpeta de investigaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elementos de la FGR decomisaron 60 paquetes de coca\u00edna ocultos en un contenedor proveniente de Bolivia Autoridades de&nbsp;Zapopan, Jalisco,&nbsp;aseguraron un contenedor con casi 60 kilos de coca\u00edna en el interior de un contenedor, procedente de Bolivia. En un comunicado, la\u00a0Fiscal\u00eda General de la Rep\u00fablica\u00a0inform\u00f3 que se integra una carpeta de investigaci\u00f3n contra quienes resulten responsables [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-10491","post","type-post","status-publish","format-standard","category-policiaca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aseguran 60 Kilos de Coca\u00edna Ocultos en Contenedor en Zapopan; Proven\u00eda de Bolivia - Peri\u00f3dico Realidades<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/periodicorealidades.com\/index.php\/2024\/02\/23\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aseguran 60 Kilos de Coca\u00edna Ocultos en Contenedor en Zapopan; Proven\u00eda de Bolivia - Peri\u00f3dico Realidades\" \/>\n<meta property=\"og:description\" content=\"Elementos de la FGR decomisaron 60 paquetes de coca\u00edna ocultos en un contenedor proveniente de Bolivia Autoridades de&nbsp;Zapopan, Jalisco,&nbsp;aseguraron un contenedor con casi 60 kilos de coca\u00edna en el interior de un contenedor, procedente de Bolivia. En un comunicado, la\u00a0Fiscal\u00eda General de la Rep\u00fablica\u00a0inform\u00f3 que se integra una carpeta de investigaci\u00f3n contra quienes resulten responsables [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/periodicorealidades.com\/index.php\/2024\/02\/23\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\/\" \/>\n<meta property=\"og:site_name\" content=\"Peri\u00f3dico Realidades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-23T20:09:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-23T20:09:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2024\/02\/hallazgo-cocaina-zapopan-jalisco_0.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Arcelia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arcelia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/02\\\/23\\\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/02\\\/23\\\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\\\/\"},\"author\":{\"name\":\"Arcelia\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/ed60e33c6767be45db655d22ad0c15c4\"},\"headline\":\"Aseguran 60 Kilos de Coca\u00edna Ocultos en Contenedor en Zapopan; Proven\u00eda de Bolivia\",\"datePublished\":\"2024-02-23T20:09:06+00:00\",\"dateModified\":\"2024-02-23T20:09:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/02\\\/23\\\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\\\/\"},\"wordCount\":205,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/02\\\/23\\\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/static-live.nmas.com.mx\\\/nmas-news\\\/styles\\\/large\\\/cloud-storage\\\/2024-02\\\/cocaina-zapopan.jpg.webp?itok=_1UooDPu\",\"articleSection\":[\"Policiaca\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/02\\\/23\\\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/02\\\/23\\\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/02\\\/23\\\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\\\/\",\"name\":\"Aseguran 60 Kilos de Coca\u00edna Ocultos en Contenedor en Zapopan; Proven\u00eda de Bolivia - Peri\u00f3dico Realidades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/02\\\/23\\\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/02\\\/23\\\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/static-live.nmas.com.mx\\\/nmas-news\\\/styles\\\/large\\\/cloud-storage\\\/2024-02\\\/cocaina-zapopan.jpg.webp?itok=_1UooDPu\",\"datePublished\":\"2024-02-23T20:09:06+00:00\",\"dateModified\":\"2024-02-23T20:09:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/02\\\/23\\\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/02\\\/23\\\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/02\\\/23\\\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/static-live.nmas.com.mx\\\/nmas-news\\\/styles\\\/large\\\/cloud-storage\\\/2024-02\\\/cocaina-zapopan.jpg.webp?itok=_1UooDPu\",\"contentUrl\":\"https:\\\/\\\/static-live.nmas.com.mx\\\/nmas-news\\\/styles\\\/large\\\/cloud-storage\\\/2024-02\\\/cocaina-zapopan.jpg.webp?itok=_1UooDPu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/02\\\/23\\\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/periodicorealidades.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aseguran 60 Kilos de Coca\u00edna Ocultos en Contenedor en Zapopan; Proven\u00eda de Bolivia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"name\":\"Peri\u00f3dico Realidades\",\"description\":\"M\u00e9dio de comunicaci\u00f3n en Nayarit\",\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/periodicorealidades.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\",\"name\":\"Peri\u00f3dico Realidades\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"contentUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"width\":709,\"height\":709,\"caption\":\"Peri\u00f3dico Realidades\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/periodicorealidades.denayarit?mibextid=LQQJ4d\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/ed60e33c6767be45db655d22ad0c15c4\",\"name\":\"Arcelia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g\",\"caption\":\"Arcelia\"},\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/author\\\/editor-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aseguran 60 Kilos de Coca\u00edna Ocultos en Contenedor en Zapopan; Proven\u00eda de Bolivia - Peri\u00f3dico Realidades","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/periodicorealidades.com\/index.php\/2024\/02\/23\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\/","og_locale":"es_MX","og_type":"article","og_title":"Aseguran 60 Kilos de Coca\u00edna Ocultos en Contenedor en Zapopan; Proven\u00eda de Bolivia - Peri\u00f3dico Realidades","og_description":"Elementos de la FGR decomisaron 60 paquetes de coca\u00edna ocultos en un contenedor proveniente de Bolivia Autoridades de&nbsp;Zapopan, Jalisco,&nbsp;aseguraron un contenedor con casi 60 kilos de coca\u00edna en el interior de un contenedor, procedente de Bolivia. En un comunicado, la\u00a0Fiscal\u00eda General de la Rep\u00fablica\u00a0inform\u00f3 que se integra una carpeta de investigaci\u00f3n contra quienes resulten responsables [&hellip;]","og_url":"https:\/\/periodicorealidades.com\/index.php\/2024\/02\/23\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\/","og_site_name":"Peri\u00f3dico Realidades","article_publisher":"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d","article_published_time":"2024-02-23T20:09:06+00:00","article_modified_time":"2024-02-23T20:09:07+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2024\/02\/hallazgo-cocaina-zapopan-jalisco_0.webp","type":"image\/webp"}],"author":"Arcelia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Arcelia","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/02\/23\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\/#article","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/02\/23\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\/"},"author":{"name":"Arcelia","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/ed60e33c6767be45db655d22ad0c15c4"},"headline":"Aseguran 60 Kilos de Coca\u00edna Ocultos en Contenedor en Zapopan; Proven\u00eda de Bolivia","datePublished":"2024-02-23T20:09:06+00:00","dateModified":"2024-02-23T20:09:07+00:00","mainEntityOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/02\/23\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\/"},"wordCount":205,"commentCount":0,"publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/02\/23\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\/#primaryimage"},"thumbnailUrl":"https:\/\/static-live.nmas.com.mx\/nmas-news\/styles\/large\/cloud-storage\/2024-02\/cocaina-zapopan.jpg.webp?itok=_1UooDPu","articleSection":["Policiaca"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/periodicorealidades.com\/index.php\/2024\/02\/23\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/02\/23\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\/","url":"https:\/\/periodicorealidades.com\/index.php\/2024\/02\/23\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\/","name":"Aseguran 60 Kilos de Coca\u00edna Ocultos en Contenedor en Zapopan; Proven\u00eda de Bolivia - Peri\u00f3dico Realidades","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/02\/23\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\/#primaryimage"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/02\/23\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\/#primaryimage"},"thumbnailUrl":"https:\/\/static-live.nmas.com.mx\/nmas-news\/styles\/large\/cloud-storage\/2024-02\/cocaina-zapopan.jpg.webp?itok=_1UooDPu","datePublished":"2024-02-23T20:09:06+00:00","dateModified":"2024-02-23T20:09:07+00:00","breadcrumb":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/02\/23\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/periodicorealidades.com\/index.php\/2024\/02\/23\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/02\/23\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\/#primaryimage","url":"https:\/\/static-live.nmas.com.mx\/nmas-news\/styles\/large\/cloud-storage\/2024-02\/cocaina-zapopan.jpg.webp?itok=_1UooDPu","contentUrl":"https:\/\/static-live.nmas.com.mx\/nmas-news\/styles\/large\/cloud-storage\/2024-02\/cocaina-zapopan.jpg.webp?itok=_1UooDPu"},{"@type":"BreadcrumbList","@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/02\/23\/aseguran-60-kilos-de-cocaina-ocultos-en-contenedor-en-zapopan-provenia-de-bolivia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/periodicorealidades.com\/"},{"@type":"ListItem","position":2,"name":"Aseguran 60 Kilos de Coca\u00edna Ocultos en Contenedor en Zapopan; Proven\u00eda de Bolivia"}]},{"@type":"WebSite","@id":"https:\/\/periodicorealidades.com\/#website","url":"https:\/\/periodicorealidades.com\/","name":"Peri\u00f3dico Realidades","description":"M\u00e9dio de comunicaci\u00f3n en Nayarit","publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/periodicorealidades.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/periodicorealidades.com\/#organization","name":"Peri\u00f3dico Realidades","url":"https:\/\/periodicorealidades.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/","url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","contentUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","width":709,"height":709,"caption":"Peri\u00f3dico Realidades"},"image":{"@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d"]},{"@type":"Person","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/ed60e33c6767be45db655d22ad0c15c4","name":"Arcelia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g","caption":"Arcelia"},"url":"https:\/\/periodicorealidades.com\/index.php\/author\/editor-2\/"}]}},"_links":{"self":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/10491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/comments?post=10491"}],"version-history":[{"count":0,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/10491\/revisions"}],"wp:attachment":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/media?parent=10491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/categories?post=10491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/tags?post=10491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}