{"id":15715,"date":"2024-04-29T22:07:01","date_gmt":"2024-04-30T05:07:01","guid":{"rendered":"https:\/\/periodicorealidades.com\/?p=15715"},"modified":"2024-04-29T22:07:02","modified_gmt":"2024-04-30T05:07:02","slug":"el-98-de-escuelas-en-mexico-promueven-obesidad-y-diabetes-en-menores-acusan-organizaciones","status":"publish","type":"post","link":"https:\/\/periodicorealidades.com\/index.php\/2024\/04\/29\/el-98-de-escuelas-en-mexico-promueven-obesidad-y-diabetes-en-menores-acusan-organizaciones\/","title":{"rendered":"El 98 % de escuelas en M\u00e9xico promueven obesidad y diabetes en menores, acusan organizaciones"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El 98 por ciento de las escuelas en M\u00e9xico promueven obesidad y diabetes en las infancias y adolescencias, advirtieron este lunes organizaciones civiles, quienes exigieron a la Secretar\u00eda de Educaci\u00f3n P\u00fablica (SEP emitir nuevos lineamientos para la venta de alimentos y bebidas dentro de los recintos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las escuelas son parte del problema, nueve de cada 10 ofertan diariamente bebidas azucaradas, golosinas, frituras y dulces y, solo dos de cada 10 disponen de agua y alimentos naturales, provocando el consumo promedio de m\u00e1s de 500 calor\u00edas extras en los escolares&#8221;, se\u00f1alaron activistas en una conferencia de prensa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto, pese a que en M\u00e9xico existe una ley que proh\u00edbe la venta de comida &#8216;chatarra (no saludable) en las escuelas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con esta legislaci\u00f3n, desde 2014, solo se deben ofrecer alimentos naturales como frutas, verduras, cereales integrales, semillas, leguminosas secas y agua simple a libre demanda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">#EnVivo Las escuelas en M\u00e9xico promueven #obesidad y #Diabetes en ni\u00f1as, ni\u00f1os y adolescentes. En el marco del #diadelani\u00f1ayelni\u00f1o llamamos a las autoridades a proteger sus derechos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ent\u00e9rate<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Publicado por El Poder del<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Consumidor en Lunes, 29 de abril de 2024<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 2023, se reform\u00f3 la Ley General de Educaci\u00f3n donde se establece que la SEP tiene hasta junio de 2024 para emitir nuevos lineamientos y prohibir todos los productos chatarras en las escuelas del pa\u00eds; sin embargo, denunciaron que estas directrices a\u00fan no han sido publicadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan la plataforma &#8216;Mi Escuela Saludable&#8217;, impulsada por las organizaciones mexicanas El Poder del Consumidor y Red por los Derechos de la Infancia (Redim), durante el ciclo escolar<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2023-2024, la mayor\u00eda de los espacios escolares en el pa\u00eds han incumplido con la regulaci\u00f3n obligatoria y sancionable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Del total de las nueve mil 582 escuelas reportadas, 79 por ciento venden refrescos, 98 % venden golosinas, dulces, frituras y\/o helados; en contraste, s\u00f3lo 19 por ciento tienen acceso a frutas, verduras y agua potable para consumo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, apenas 4 por ciento cuentan con un comit\u00e9 que vigila el cumplimiento de la ley.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy estamos frente a una crisis en las que ni\u00f1os, ni\u00f1as y adolescentes no tienen acceso a alimentos saludables y agua potable, y en cambio, 98 por ciento de las escuelas venden de forma ilimitada refrescos, dulces, galletas, frituras y dulces, y a veces como \u00fanica opci\u00f3n de consumo; da\u00f1ando su salud, nutrici\u00f3n y aprendizaje&#8221;, acusaron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ana Abreu, investigadora del Instituto Nacional de Salud<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">P\u00fablica (INSP), asegur\u00f3 que la ley que proh\u00edbe la preparaci\u00f3n, venta y distribuci\u00f3n de alimentos y bebidas con bajo valor nutricional dentro de las escuelas, reducir\u00e1 la prevalencia de obesidad infantil hasta un 7 % anual y si la regulaci\u00f3n se aplica efectivamente en un 80 por ciento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Por ello, es urgente contar con lineamientos claros y de f\u00e1cil implementaci\u00f3n, as\u00ed como el monitoreo continuo, incluyendo la aplicaci\u00f3n de sanciones cuando sean necesarias. Esto asegurar\u00e1 el bienestar de ni\u00f1as, ni\u00f1os y adolescentes en las escuelas&#8221;, expuso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto, Tania Ram\u00edrez, directora ejecutiva de la Redim, declar\u00f3 que la reforma a la ley y el reconocimiento al derecho a la alimentaci\u00f3n adecuada son parte del marco de derechos que deben ser velados y garantizados para la infancia mexicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, hicieron un llamado a las candidatas y el candidato a la presidencia para proteger y garantizar entornos saludables a ni\u00f1as, ni\u00f1os y adolescentes, y a la SEP a dise\u00f1ar e implementar los lineamientos para la venta de alimentos y bebidas de acuerdo a la Ley General de Educaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 98 por ciento de las escuelas en M\u00e9xico promueven obesidad y diabetes en las infancias y adolescencias, advirtieron este lunes organizaciones civiles, quienes exigieron a la Secretar\u00eda de Educaci\u00f3n P\u00fablica (SEP emitir nuevos lineamientos para la venta de alimentos y bebidas dentro de los recintos. Las escuelas son parte del problema, nueve de cada [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-15715","post","type-post","status-publish","format-standard","category-nacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El 98 % de escuelas en M\u00e9xico promueven obesidad y diabetes en menores, acusan organizaciones - Peri\u00f3dico Realidades<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/periodicorealidades.com\/index.php\/2024\/04\/29\/el-98-de-escuelas-en-mexico-promueven-obesidad-y-diabetes-en-menores-acusan-organizaciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El 98 % de escuelas en M\u00e9xico promueven obesidad y diabetes en menores, acusan organizaciones - Peri\u00f3dico Realidades\" \/>\n<meta property=\"og:description\" content=\"El 98 por ciento de las escuelas en M\u00e9xico promueven obesidad y diabetes en las infancias y adolescencias, advirtieron este lunes organizaciones civiles, quienes exigieron a la Secretar\u00eda de Educaci\u00f3n P\u00fablica (SEP emitir nuevos lineamientos para la venta de alimentos y bebidas dentro de los recintos. Las escuelas son parte del problema, nueve de cada [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/periodicorealidades.com\/index.php\/2024\/04\/29\/el-98-de-escuelas-en-mexico-promueven-obesidad-y-diabetes-en-menores-acusan-organizaciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Peri\u00f3dico Realidades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-30T05:07:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-30T05:07:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2024\/04\/F59FB3E9-3EE6-447F-939A-98CB10001EF0.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Aracely\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aracely\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/04\\\/29\\\/el-98-de-escuelas-en-mexico-promueven-obesidad-y-diabetes-en-menores-acusan-organizaciones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/04\\\/29\\\/el-98-de-escuelas-en-mexico-promueven-obesidad-y-diabetes-en-menores-acusan-organizaciones\\\/\"},\"author\":{\"name\":\"Aracely\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/df6af7553a1189bf973891c9f268acf3\"},\"headline\":\"El 98 % de escuelas en M\u00e9xico promueven obesidad y diabetes en menores, acusan organizaciones\",\"datePublished\":\"2024-04-30T05:07:01+00:00\",\"dateModified\":\"2024-04-30T05:07:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/04\\\/29\\\/el-98-de-escuelas-en-mexico-promueven-obesidad-y-diabetes-en-menores-acusan-organizaciones\\\/\"},\"wordCount\":613,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"articleSection\":[\"Nacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/04\\\/29\\\/el-98-de-escuelas-en-mexico-promueven-obesidad-y-diabetes-en-menores-acusan-organizaciones\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/04\\\/29\\\/el-98-de-escuelas-en-mexico-promueven-obesidad-y-diabetes-en-menores-acusan-organizaciones\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/04\\\/29\\\/el-98-de-escuelas-en-mexico-promueven-obesidad-y-diabetes-en-menores-acusan-organizaciones\\\/\",\"name\":\"El 98 % de escuelas en M\u00e9xico promueven obesidad y diabetes en menores, acusan organizaciones - Peri\u00f3dico Realidades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\"},\"datePublished\":\"2024-04-30T05:07:01+00:00\",\"dateModified\":\"2024-04-30T05:07:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/04\\\/29\\\/el-98-de-escuelas-en-mexico-promueven-obesidad-y-diabetes-en-menores-acusan-organizaciones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/04\\\/29\\\/el-98-de-escuelas-en-mexico-promueven-obesidad-y-diabetes-en-menores-acusan-organizaciones\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/04\\\/29\\\/el-98-de-escuelas-en-mexico-promueven-obesidad-y-diabetes-en-menores-acusan-organizaciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/periodicorealidades.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El 98 % de escuelas en M\u00e9xico promueven obesidad y diabetes en menores, acusan organizaciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"name\":\"Peri\u00f3dico Realidades\",\"description\":\"M\u00e9dio de comunicaci\u00f3n en Nayarit\",\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/periodicorealidades.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\",\"name\":\"Peri\u00f3dico Realidades\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"contentUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"width\":709,\"height\":709,\"caption\":\"Peri\u00f3dico Realidades\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/periodicorealidades.denayarit?mibextid=LQQJ4d\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/df6af7553a1189bf973891c9f268acf3\",\"name\":\"Aracely\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ee9d8e9d2e4a359c987c139b9cd012c6c076ea539e43d023be2af04cf533e91?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ee9d8e9d2e4a359c987c139b9cd012c6c076ea539e43d023be2af04cf533e91?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ee9d8e9d2e4a359c987c139b9cd012c6c076ea539e43d023be2af04cf533e91?s=96&d=mm&r=g\",\"caption\":\"Aracely\"},\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/author\\\/aracelyreali\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El 98 % de escuelas en M\u00e9xico promueven obesidad y diabetes en menores, acusan organizaciones - Peri\u00f3dico Realidades","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/periodicorealidades.com\/index.php\/2024\/04\/29\/el-98-de-escuelas-en-mexico-promueven-obesidad-y-diabetes-en-menores-acusan-organizaciones\/","og_locale":"es_MX","og_type":"article","og_title":"El 98 % de escuelas en M\u00e9xico promueven obesidad y diabetes en menores, acusan organizaciones - Peri\u00f3dico Realidades","og_description":"El 98 por ciento de las escuelas en M\u00e9xico promueven obesidad y diabetes en las infancias y adolescencias, advirtieron este lunes organizaciones civiles, quienes exigieron a la Secretar\u00eda de Educaci\u00f3n P\u00fablica (SEP emitir nuevos lineamientos para la venta de alimentos y bebidas dentro de los recintos. Las escuelas son parte del problema, nueve de cada [&hellip;]","og_url":"https:\/\/periodicorealidades.com\/index.php\/2024\/04\/29\/el-98-de-escuelas-en-mexico-promueven-obesidad-y-diabetes-en-menores-acusan-organizaciones\/","og_site_name":"Peri\u00f3dico Realidades","article_publisher":"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d","article_published_time":"2024-04-30T05:07:01+00:00","article_modified_time":"2024-04-30T05:07:02+00:00","og_image":[{"width":1536,"height":1024,"url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2024\/04\/F59FB3E9-3EE6-447F-939A-98CB10001EF0.jpeg","type":"image\/jpeg"}],"author":"Aracely","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Aracely","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/04\/29\/el-98-de-escuelas-en-mexico-promueven-obesidad-y-diabetes-en-menores-acusan-organizaciones\/#article","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/04\/29\/el-98-de-escuelas-en-mexico-promueven-obesidad-y-diabetes-en-menores-acusan-organizaciones\/"},"author":{"name":"Aracely","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/df6af7553a1189bf973891c9f268acf3"},"headline":"El 98 % de escuelas en M\u00e9xico promueven obesidad y diabetes en menores, acusan organizaciones","datePublished":"2024-04-30T05:07:01+00:00","dateModified":"2024-04-30T05:07:02+00:00","mainEntityOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/04\/29\/el-98-de-escuelas-en-mexico-promueven-obesidad-y-diabetes-en-menores-acusan-organizaciones\/"},"wordCount":613,"commentCount":0,"publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"articleSection":["Nacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/periodicorealidades.com\/index.php\/2024\/04\/29\/el-98-de-escuelas-en-mexico-promueven-obesidad-y-diabetes-en-menores-acusan-organizaciones\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/04\/29\/el-98-de-escuelas-en-mexico-promueven-obesidad-y-diabetes-en-menores-acusan-organizaciones\/","url":"https:\/\/periodicorealidades.com\/index.php\/2024\/04\/29\/el-98-de-escuelas-en-mexico-promueven-obesidad-y-diabetes-en-menores-acusan-organizaciones\/","name":"El 98 % de escuelas en M\u00e9xico promueven obesidad y diabetes en menores, acusan organizaciones - Peri\u00f3dico Realidades","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/#website"},"datePublished":"2024-04-30T05:07:01+00:00","dateModified":"2024-04-30T05:07:02+00:00","breadcrumb":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/04\/29\/el-98-de-escuelas-en-mexico-promueven-obesidad-y-diabetes-en-menores-acusan-organizaciones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/periodicorealidades.com\/index.php\/2024\/04\/29\/el-98-de-escuelas-en-mexico-promueven-obesidad-y-diabetes-en-menores-acusan-organizaciones\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/04\/29\/el-98-de-escuelas-en-mexico-promueven-obesidad-y-diabetes-en-menores-acusan-organizaciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/periodicorealidades.com\/"},{"@type":"ListItem","position":2,"name":"El 98 % de escuelas en M\u00e9xico promueven obesidad y diabetes en menores, acusan organizaciones"}]},{"@type":"WebSite","@id":"https:\/\/periodicorealidades.com\/#website","url":"https:\/\/periodicorealidades.com\/","name":"Peri\u00f3dico Realidades","description":"M\u00e9dio de comunicaci\u00f3n en Nayarit","publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/periodicorealidades.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/periodicorealidades.com\/#organization","name":"Peri\u00f3dico Realidades","url":"https:\/\/periodicorealidades.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/","url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","contentUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","width":709,"height":709,"caption":"Peri\u00f3dico Realidades"},"image":{"@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d"]},{"@type":"Person","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/df6af7553a1189bf973891c9f268acf3","name":"Aracely","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9ee9d8e9d2e4a359c987c139b9cd012c6c076ea539e43d023be2af04cf533e91?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9ee9d8e9d2e4a359c987c139b9cd012c6c076ea539e43d023be2af04cf533e91?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ee9d8e9d2e4a359c987c139b9cd012c6c076ea539e43d023be2af04cf533e91?s=96&d=mm&r=g","caption":"Aracely"},"url":"https:\/\/periodicorealidades.com\/index.php\/author\/aracelyreali\/"}]}},"_links":{"self":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/15715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/comments?post=15715"}],"version-history":[{"count":0,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/15715\/revisions"}],"wp:attachment":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/media?parent=15715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/categories?post=15715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/tags?post=15715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}