{"id":20268,"date":"2024-07-01T23:01:06","date_gmt":"2024-07-02T06:01:06","guid":{"rendered":"https:\/\/periodicorealidades.com\/?p=20268"},"modified":"2024-07-01T23:01:07","modified_gmt":"2024-07-02T06:01:07","slug":"huracan-beryl-podria-impactar-a-mexico-dos-veces","status":"publish","type":"post","link":"https:\/\/periodicorealidades.com\/index.php\/2024\/07\/01\/huracan-beryl-podria-impactar-a-mexico-dos-veces\/","title":{"rendered":"Hurac\u00e1n &#8220;Beryl&#8221; podr\u00eda impactar a M\u00e9xico dos veces"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Autoridades de los tres niveles de gobierno en M\u00e9xico se coordinan ante la presencia del hurac\u00e1n &#8220;Beryl&#8221;, actualmente de categor\u00eda 4, y que podr\u00eda impactar dos veces al pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En conferencia de prensa, la coordinadora general del Servicio Meteorol\u00f3gico Nacional (SMN), Alejandra Margarita M\u00e9ndez Gir\u00f3n, inform\u00f3 que durante este lunes, el cicl\u00f3n mantendr\u00e1 su desplazamiento sobre el Mar Caribe, a una distancia de 2 mil<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">600 km de las costas de Quintana Roo, y mantendr\u00e1 desplazamiento hacia el oeste-noroeste, con vientos de 230 km\/h y rachas de 280 km\/h.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para el martes y mi\u00e9rcoles, el hurac\u00e1n se desplazar\u00e1 sobre el Mar Caribe donde encontrar\u00e1 viento fuerte en la altura, por lo que podr\u00eda perder intensidad y degradarse a un hurac\u00e1n de categor\u00eda 2, con vientos de 165 km\/h y rachas de 205 km\/h.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el mi\u00e9rcoles, continuar\u00e1 desplaz\u00e1ndose al oeste-noreste, y se ubicar\u00e1 aproximadamente a 900 km al este de las costas de Quintana Roo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed, se espera que para el d\u00eda jueves, &#8220;Beryl&#8221; contin\u00fae desplaz\u00e1ndose hacia las costas de Quintana Roo, como un hurac\u00e1n de categor\u00eda 1 o 2, con vientos de 150 km\/h y rachas de 205 km\/h. Ser\u00e1 a partir de ese d\u00eda que sus bandas nubosas empezar\u00e1n a afectar los estados de la Pen\u00ednsula de Yucat\u00e1n, donde se prev\u00e9n lluvias torrenciales en Yucat\u00e1n y Quintana Roo; intensas en Campeche, adem\u00e1s de vientos de 110 a 130 km\/h, oleaje de 4 a 6 metros de altura y posible formaci\u00f3n de trombas marinas, adem\u00e1s de lluvias de fuertes a muy fuertes en estados del sureste, oriente y centro de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si el hurac\u00e1n contin\u00faa movi\u00e9ndose al oeste-noroeste, podr\u00eda tocar tierra el jueves por la noche o madrugada del viernes sobre la porci\u00f3n centro-sur del estado de Quintana Roo, con vientos mayores a los 120 km\/h.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el viernes, se espera que &#8220;Beryl&#8221; cruce la porci\u00f3n centro-sur de la Pen\u00ednsula de Yucat\u00e1n, para ingresar el d\u00eda s\u00e1bado al sur del Golfo de M\u00e9xico como una tormenta tropical con vientos de 63 a 119 km\/h, donde permanecer\u00e1 el s\u00e1bado y domingo, con una trayectoria hacia las costas de Veracruz y<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamaulipas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Del jueves 4 de julio al domingo 7, se esperan fuertes lluvias en Campeche, Oaxaca, Chiapas, Quintana Roo, Tabasco, sur de Veracruz y Yucat\u00e1n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con informaci\u00f3n de L\u00f3pez-D\u00f3riga Digital<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Autoridades de los tres niveles de gobierno en M\u00e9xico se coordinan ante la presencia del hurac\u00e1n &#8220;Beryl&#8221;, actualmente de categor\u00eda 4, y que podr\u00eda impactar dos veces al pa\u00eds. En conferencia de prensa, la coordinadora general del Servicio Meteorol\u00f3gico Nacional (SMN), Alejandra Margarita M\u00e9ndez Gir\u00f3n, inform\u00f3 que durante este lunes, el cicl\u00f3n mantendr\u00e1 su desplazamiento [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":20269,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-20268","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hurac\u00e1n &quot;Beryl&quot; podr\u00eda impactar a M\u00e9xico dos veces - Peri\u00f3dico Realidades<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/periodicorealidades.com\/index.php\/2024\/07\/01\/huracan-beryl-podria-impactar-a-mexico-dos-veces\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hurac\u00e1n &quot;Beryl&quot; podr\u00eda impactar a M\u00e9xico dos veces - Peri\u00f3dico Realidades\" \/>\n<meta property=\"og:description\" content=\"Autoridades de los tres niveles de gobierno en M\u00e9xico se coordinan ante la presencia del hurac\u00e1n &#8220;Beryl&#8221;, actualmente de categor\u00eda 4, y que podr\u00eda impactar dos veces al pa\u00eds. En conferencia de prensa, la coordinadora general del Servicio Meteorol\u00f3gico Nacional (SMN), Alejandra Margarita M\u00e9ndez Gir\u00f3n, inform\u00f3 que durante este lunes, el cicl\u00f3n mantendr\u00e1 su desplazamiento [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/periodicorealidades.com\/index.php\/2024\/07\/01\/huracan-beryl-podria-impactar-a-mexico-dos-veces\/\" \/>\n<meta property=\"og:site_name\" content=\"Peri\u00f3dico Realidades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-02T06:01:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-02T06:01:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2024\/07\/FC1AC9AF-B32D-4D0A-82E8-BAAC69A729E5.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1531\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Aracely\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aracely\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/07\\\/01\\\/huracan-beryl-podria-impactar-a-mexico-dos-veces\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/07\\\/01\\\/huracan-beryl-podria-impactar-a-mexico-dos-veces\\\/\"},\"author\":{\"name\":\"Aracely\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/df6af7553a1189bf973891c9f268acf3\"},\"headline\":\"Hurac\u00e1n &#8220;Beryl&#8221; podr\u00eda impactar a M\u00e9xico dos veces\",\"datePublished\":\"2024-07-02T06:01:06+00:00\",\"dateModified\":\"2024-07-02T06:01:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/07\\\/01\\\/huracan-beryl-podria-impactar-a-mexico-dos-veces\\\/\"},\"wordCount\":425,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/07\\\/01\\\/huracan-beryl-podria-impactar-a-mexico-dos-veces\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/FC1AC9AF-B32D-4D0A-82E8-BAAC69A729E5.jpeg\",\"articleSection\":[\"Nacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/07\\\/01\\\/huracan-beryl-podria-impactar-a-mexico-dos-veces\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/07\\\/01\\\/huracan-beryl-podria-impactar-a-mexico-dos-veces\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/07\\\/01\\\/huracan-beryl-podria-impactar-a-mexico-dos-veces\\\/\",\"name\":\"Hurac\u00e1n \\\"Beryl\\\" podr\u00eda impactar a M\u00e9xico dos veces - Peri\u00f3dico Realidades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/07\\\/01\\\/huracan-beryl-podria-impactar-a-mexico-dos-veces\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/07\\\/01\\\/huracan-beryl-podria-impactar-a-mexico-dos-veces\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/FC1AC9AF-B32D-4D0A-82E8-BAAC69A729E5.jpeg\",\"datePublished\":\"2024-07-02T06:01:06+00:00\",\"dateModified\":\"2024-07-02T06:01:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/07\\\/01\\\/huracan-beryl-podria-impactar-a-mexico-dos-veces\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/07\\\/01\\\/huracan-beryl-podria-impactar-a-mexico-dos-veces\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/07\\\/01\\\/huracan-beryl-podria-impactar-a-mexico-dos-veces\\\/#primaryimage\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/FC1AC9AF-B32D-4D0A-82E8-BAAC69A729E5.jpeg\",\"contentUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/FC1AC9AF-B32D-4D0A-82E8-BAAC69A729E5.jpeg\",\"width\":1531,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2024\\\/07\\\/01\\\/huracan-beryl-podria-impactar-a-mexico-dos-veces\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/periodicorealidades.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hurac\u00e1n &#8220;Beryl&#8221; podr\u00eda impactar a M\u00e9xico dos veces\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"name\":\"Peri\u00f3dico Realidades\",\"description\":\"M\u00e9dio de comunicaci\u00f3n en Nayarit\",\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/periodicorealidades.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\",\"name\":\"Peri\u00f3dico Realidades\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"contentUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"width\":709,\"height\":709,\"caption\":\"Peri\u00f3dico Realidades\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/periodicorealidades.denayarit?mibextid=LQQJ4d\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/df6af7553a1189bf973891c9f268acf3\",\"name\":\"Aracely\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ee9d8e9d2e4a359c987c139b9cd012c6c076ea539e43d023be2af04cf533e91?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ee9d8e9d2e4a359c987c139b9cd012c6c076ea539e43d023be2af04cf533e91?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ee9d8e9d2e4a359c987c139b9cd012c6c076ea539e43d023be2af04cf533e91?s=96&d=mm&r=g\",\"caption\":\"Aracely\"},\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/author\\\/aracelyreali\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hurac\u00e1n \"Beryl\" podr\u00eda impactar a M\u00e9xico dos veces - Peri\u00f3dico Realidades","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/periodicorealidades.com\/index.php\/2024\/07\/01\/huracan-beryl-podria-impactar-a-mexico-dos-veces\/","og_locale":"es_MX","og_type":"article","og_title":"Hurac\u00e1n \"Beryl\" podr\u00eda impactar a M\u00e9xico dos veces - Peri\u00f3dico Realidades","og_description":"Autoridades de los tres niveles de gobierno en M\u00e9xico se coordinan ante la presencia del hurac\u00e1n &#8220;Beryl&#8221;, actualmente de categor\u00eda 4, y que podr\u00eda impactar dos veces al pa\u00eds. En conferencia de prensa, la coordinadora general del Servicio Meteorol\u00f3gico Nacional (SMN), Alejandra Margarita M\u00e9ndez Gir\u00f3n, inform\u00f3 que durante este lunes, el cicl\u00f3n mantendr\u00e1 su desplazamiento [&hellip;]","og_url":"https:\/\/periodicorealidades.com\/index.php\/2024\/07\/01\/huracan-beryl-podria-impactar-a-mexico-dos-veces\/","og_site_name":"Peri\u00f3dico Realidades","article_publisher":"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d","article_published_time":"2024-07-02T06:01:06+00:00","article_modified_time":"2024-07-02T06:01:07+00:00","og_image":[{"width":1531,"height":900,"url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2024\/07\/FC1AC9AF-B32D-4D0A-82E8-BAAC69A729E5.jpeg","type":"image\/jpeg"}],"author":"Aracely","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Aracely","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/07\/01\/huracan-beryl-podria-impactar-a-mexico-dos-veces\/#article","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/07\/01\/huracan-beryl-podria-impactar-a-mexico-dos-veces\/"},"author":{"name":"Aracely","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/df6af7553a1189bf973891c9f268acf3"},"headline":"Hurac\u00e1n &#8220;Beryl&#8221; podr\u00eda impactar a M\u00e9xico dos veces","datePublished":"2024-07-02T06:01:06+00:00","dateModified":"2024-07-02T06:01:07+00:00","mainEntityOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/07\/01\/huracan-beryl-podria-impactar-a-mexico-dos-veces\/"},"wordCount":425,"commentCount":0,"publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/07\/01\/huracan-beryl-podria-impactar-a-mexico-dos-veces\/#primaryimage"},"thumbnailUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2024\/07\/FC1AC9AF-B32D-4D0A-82E8-BAAC69A729E5.jpeg","articleSection":["Nacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/periodicorealidades.com\/index.php\/2024\/07\/01\/huracan-beryl-podria-impactar-a-mexico-dos-veces\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/07\/01\/huracan-beryl-podria-impactar-a-mexico-dos-veces\/","url":"https:\/\/periodicorealidades.com\/index.php\/2024\/07\/01\/huracan-beryl-podria-impactar-a-mexico-dos-veces\/","name":"Hurac\u00e1n \"Beryl\" podr\u00eda impactar a M\u00e9xico dos veces - Peri\u00f3dico Realidades","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/07\/01\/huracan-beryl-podria-impactar-a-mexico-dos-veces\/#primaryimage"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/07\/01\/huracan-beryl-podria-impactar-a-mexico-dos-veces\/#primaryimage"},"thumbnailUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2024\/07\/FC1AC9AF-B32D-4D0A-82E8-BAAC69A729E5.jpeg","datePublished":"2024-07-02T06:01:06+00:00","dateModified":"2024-07-02T06:01:07+00:00","breadcrumb":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/07\/01\/huracan-beryl-podria-impactar-a-mexico-dos-veces\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/periodicorealidades.com\/index.php\/2024\/07\/01\/huracan-beryl-podria-impactar-a-mexico-dos-veces\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/07\/01\/huracan-beryl-podria-impactar-a-mexico-dos-veces\/#primaryimage","url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2024\/07\/FC1AC9AF-B32D-4D0A-82E8-BAAC69A729E5.jpeg","contentUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2024\/07\/FC1AC9AF-B32D-4D0A-82E8-BAAC69A729E5.jpeg","width":1531,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/periodicorealidades.com\/index.php\/2024\/07\/01\/huracan-beryl-podria-impactar-a-mexico-dos-veces\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/periodicorealidades.com\/"},{"@type":"ListItem","position":2,"name":"Hurac\u00e1n &#8220;Beryl&#8221; podr\u00eda impactar a M\u00e9xico dos veces"}]},{"@type":"WebSite","@id":"https:\/\/periodicorealidades.com\/#website","url":"https:\/\/periodicorealidades.com\/","name":"Peri\u00f3dico Realidades","description":"M\u00e9dio de comunicaci\u00f3n en Nayarit","publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/periodicorealidades.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/periodicorealidades.com\/#organization","name":"Peri\u00f3dico Realidades","url":"https:\/\/periodicorealidades.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/","url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","contentUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","width":709,"height":709,"caption":"Peri\u00f3dico Realidades"},"image":{"@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d"]},{"@type":"Person","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/df6af7553a1189bf973891c9f268acf3","name":"Aracely","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9ee9d8e9d2e4a359c987c139b9cd012c6c076ea539e43d023be2af04cf533e91?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9ee9d8e9d2e4a359c987c139b9cd012c6c076ea539e43d023be2af04cf533e91?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ee9d8e9d2e4a359c987c139b9cd012c6c076ea539e43d023be2af04cf533e91?s=96&d=mm&r=g","caption":"Aracely"},"url":"https:\/\/periodicorealidades.com\/index.php\/author\/aracelyreali\/"}]}},"_links":{"self":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/20268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/comments?post=20268"}],"version-history":[{"count":0,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/20268\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/media\/20269"}],"wp:attachment":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/media?parent=20268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/categories?post=20268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/tags?post=20268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}