{"id":207,"date":"2023-10-07T05:40:56","date_gmt":"2023-10-07T05:40:56","guid":{"rendered":"https:\/\/periodicorealidades.com\/?p=207"},"modified":"2023-10-07T05:40:56","modified_gmt":"2023-10-07T05:40:56","slug":"ley-monzon-es-una-realidad-en-nayarit","status":"publish","type":"post","link":"https:\/\/periodicorealidades.com\/index.php\/2023\/10\/07\/ley-monzon-es-una-realidad-en-nayarit\/","title":{"rendered":"Ley Monz\u00f3n es una realidad en Nayarit\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El diputado, H\u00e9ctor Santana, quien junto con su compa\u00f1era, Laura Monts lanzaron la propuesta, quien hoy es una ley encaminada a la protecci\u00f2n de menores de edad que se encuentran con violentadores y pierdan la patria potestad y otras figuras juridicas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por: Mildra Ben\u00edtez Robledo&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tepic, Nayarit; s\u00e0bado, 07 de octubre del 2023.-&nbsp; Este jueves &nbsp;en el pleno del Congreso local &nbsp; se aprob\u00f3 la iniciativa denominada, &#8220;Ley Monz\u00f3n&#8221;, misma que retira o niega la patria potestad, tutela y convivencia a quienes han sido acusados de feminicidio o violaci\u00f3n, para ello se adicionar\u00f3n &nbsp;y reformaron diversas disposiciones al C\u00f3digo Civil del Estado en materia de p\u00e9rdida o suspensi\u00f3n de la patria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El diputado, H\u00e9ctor Santana, quien junto con su compa\u00f1era, Laura Monts lanzaron la propuesta, coment\u00f3 que es necesario que se protejan los derechos de los ni\u00f1os, \u00a0es por eso que no pueden estar los hijos con el padre violentador, dado a que se da pie a que las siguientes v\u00edctimas sean ellos.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/10\/LAURA-MONTS-2.jpeg\" alt=\"\" class=\"wp-image-209\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En Nayarit como en todo el pa\u00eds, coment\u00f3 que se daban casos en donde el presunto &nbsp;feminicida o perpetrador de ataques sexuales, ped\u00eda la custodia de sus hijos y estaba en todo su derecho de obtenerla es por eso que hubo la necesidad de cambiar la ley, para evitar que se generen situaciones lamentables.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para concluir, H\u00e9ctor Santana, a\u00f1adi\u00f3 que el progenitor se le cancelan los derechos como padre desde que es acusado, a\u00fan cuando no se le sentencia, puesto que hay la posibilidad de ser culpable.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El diputado, H\u00e9ctor Santana, quien junto con su compa\u00f1era, Laura Monts lanzaron la propuesta, quien hoy es una ley encaminada a la protecci\u00f2n de menores de edad que se encuentran con violentadores y pierdan la patria potestad y otras figuras juridicas Por: Mildra Ben\u00edtez Robledo&nbsp; Tepic, Nayarit; s\u00e0bado, 07 de octubre del 2023.-&nbsp; Este jueves [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[],"class_list":["post-207","post","type-post","status-publish","format-standard","category-principal","category-tepic"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ley Monz\u00f3n es una realidad en Nayarit\u00a0 - Peri\u00f3dico Realidades<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/periodicorealidades.com\/index.php\/2023\/10\/07\/ley-monzon-es-una-realidad-en-nayarit\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ley Monz\u00f3n es una realidad en Nayarit\u00a0 - Peri\u00f3dico Realidades\" \/>\n<meta property=\"og:description\" content=\"El diputado, H\u00e9ctor Santana, quien junto con su compa\u00f1era, Laura Monts lanzaron la propuesta, quien hoy es una ley encaminada a la protecci\u00f2n de menores de edad que se encuentran con violentadores y pierdan la patria potestad y otras figuras juridicas Por: Mildra Ben\u00edtez Robledo&nbsp; Tepic, Nayarit; s\u00e0bado, 07 de octubre del 2023.-&nbsp; Este jueves [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/periodicorealidades.com\/index.php\/2023\/10\/07\/ley-monzon-es-una-realidad-en-nayarit\/\" \/>\n<meta property=\"og:site_name\" content=\"Peri\u00f3dico Realidades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-07T05:40:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/10\/hector-santana.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"374\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/10\\\/07\\\/ley-monzon-es-una-realidad-en-nayarit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/10\\\/07\\\/ley-monzon-es-una-realidad-en-nayarit\\\/\"},\"author\":{\"name\":\"editor\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/c27da34ee13acaec3162071a3e1c7832\"},\"headline\":\"Ley Monz\u00f3n es una realidad en Nayarit\u00a0\",\"datePublished\":\"2023-10-07T05:40:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/10\\\/07\\\/ley-monzon-es-una-realidad-en-nayarit\\\/\"},\"wordCount\":283,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/10\\\/07\\\/ley-monzon-es-una-realidad-en-nayarit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/LAURA-MONTS-2.jpeg\",\"articleSection\":[\"Principal\",\"Tepic\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/10\\\/07\\\/ley-monzon-es-una-realidad-en-nayarit\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/10\\\/07\\\/ley-monzon-es-una-realidad-en-nayarit\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/10\\\/07\\\/ley-monzon-es-una-realidad-en-nayarit\\\/\",\"name\":\"Ley Monz\u00f3n es una realidad en Nayarit\u00a0 - Peri\u00f3dico Realidades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/10\\\/07\\\/ley-monzon-es-una-realidad-en-nayarit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/10\\\/07\\\/ley-monzon-es-una-realidad-en-nayarit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/LAURA-MONTS-2.jpeg\",\"datePublished\":\"2023-10-07T05:40:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/10\\\/07\\\/ley-monzon-es-una-realidad-en-nayarit\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/10\\\/07\\\/ley-monzon-es-una-realidad-en-nayarit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/10\\\/07\\\/ley-monzon-es-una-realidad-en-nayarit\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/10\\\/07\\\/ley-monzon-es-una-realidad-en-nayarit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/periodicorealidades.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ley Monz\u00f3n es una realidad en Nayarit\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"name\":\"Peri\u00f3dico Realidades\",\"description\":\"M\u00e9dio de comunicaci\u00f3n en Nayarit\",\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/periodicorealidades.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\",\"name\":\"Peri\u00f3dico Realidades\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"contentUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"width\":709,\"height\":709,\"caption\":\"Peri\u00f3dico Realidades\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/periodicorealidades.denayarit?mibextid=LQQJ4d\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/c27da34ee13acaec3162071a3e1c7832\",\"name\":\"editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dda3c3f59ea25f4b53cd53df977b0b2628039b17268e57c944a79a00e8a56e26?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dda3c3f59ea25f4b53cd53df977b0b2628039b17268e57c944a79a00e8a56e26?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dda3c3f59ea25f4b53cd53df977b0b2628039b17268e57c944a79a00e8a56e26?s=96&d=mm&r=g\",\"caption\":\"editor\"},\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/author\\\/editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ley Monz\u00f3n es una realidad en Nayarit\u00a0 - Peri\u00f3dico Realidades","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/periodicorealidades.com\/index.php\/2023\/10\/07\/ley-monzon-es-una-realidad-en-nayarit\/","og_locale":"es_MX","og_type":"article","og_title":"Ley Monz\u00f3n es una realidad en Nayarit\u00a0 - Peri\u00f3dico Realidades","og_description":"El diputado, H\u00e9ctor Santana, quien junto con su compa\u00f1era, Laura Monts lanzaron la propuesta, quien hoy es una ley encaminada a la protecci\u00f2n de menores de edad que se encuentran con violentadores y pierdan la patria potestad y otras figuras juridicas Por: Mildra Ben\u00edtez Robledo&nbsp; Tepic, Nayarit; s\u00e0bado, 07 de octubre del 2023.-&nbsp; Este jueves [&hellip;]","og_url":"https:\/\/periodicorealidades.com\/index.php\/2023\/10\/07\/ley-monzon-es-una-realidad-en-nayarit\/","og_site_name":"Peri\u00f3dico Realidades","article_publisher":"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d","article_published_time":"2023-10-07T05:40:56+00:00","og_image":[{"width":600,"height":374,"url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/10\/hector-santana.jpg","type":"image\/jpeg"}],"author":"editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"editor","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/10\/07\/ley-monzon-es-una-realidad-en-nayarit\/#article","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/10\/07\/ley-monzon-es-una-realidad-en-nayarit\/"},"author":{"name":"editor","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/c27da34ee13acaec3162071a3e1c7832"},"headline":"Ley Monz\u00f3n es una realidad en Nayarit\u00a0","datePublished":"2023-10-07T05:40:56+00:00","mainEntityOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/10\/07\/ley-monzon-es-una-realidad-en-nayarit\/"},"wordCount":283,"commentCount":0,"publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/10\/07\/ley-monzon-es-una-realidad-en-nayarit\/#primaryimage"},"thumbnailUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/10\/LAURA-MONTS-2.jpeg","articleSection":["Principal","Tepic"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/periodicorealidades.com\/index.php\/2023\/10\/07\/ley-monzon-es-una-realidad-en-nayarit\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/10\/07\/ley-monzon-es-una-realidad-en-nayarit\/","url":"https:\/\/periodicorealidades.com\/index.php\/2023\/10\/07\/ley-monzon-es-una-realidad-en-nayarit\/","name":"Ley Monz\u00f3n es una realidad en Nayarit\u00a0 - Peri\u00f3dico Realidades","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/10\/07\/ley-monzon-es-una-realidad-en-nayarit\/#primaryimage"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/10\/07\/ley-monzon-es-una-realidad-en-nayarit\/#primaryimage"},"thumbnailUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/10\/LAURA-MONTS-2.jpeg","datePublished":"2023-10-07T05:40:56+00:00","breadcrumb":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/10\/07\/ley-monzon-es-una-realidad-en-nayarit\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/periodicorealidades.com\/index.php\/2023\/10\/07\/ley-monzon-es-una-realidad-en-nayarit\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/10\/07\/ley-monzon-es-una-realidad-en-nayarit\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/10\/07\/ley-monzon-es-una-realidad-en-nayarit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/periodicorealidades.com\/"},{"@type":"ListItem","position":2,"name":"Ley Monz\u00f3n es una realidad en Nayarit\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/periodicorealidades.com\/#website","url":"https:\/\/periodicorealidades.com\/","name":"Peri\u00f3dico Realidades","description":"M\u00e9dio de comunicaci\u00f3n en Nayarit","publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/periodicorealidades.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/periodicorealidades.com\/#organization","name":"Peri\u00f3dico Realidades","url":"https:\/\/periodicorealidades.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/","url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","contentUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","width":709,"height":709,"caption":"Peri\u00f3dico Realidades"},"image":{"@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d"]},{"@type":"Person","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/c27da34ee13acaec3162071a3e1c7832","name":"editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/dda3c3f59ea25f4b53cd53df977b0b2628039b17268e57c944a79a00e8a56e26?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dda3c3f59ea25f4b53cd53df977b0b2628039b17268e57c944a79a00e8a56e26?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dda3c3f59ea25f4b53cd53df977b0b2628039b17268e57c944a79a00e8a56e26?s=96&d=mm&r=g","caption":"editor"},"url":"https:\/\/periodicorealidades.com\/index.php\/author\/editor\/"}]}},"_links":{"self":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/comments?post=207"}],"version-history":[{"count":0,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/207\/revisions"}],"wp:attachment":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/media?parent=207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/categories?post=207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/tags?post=207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}