{"id":3337,"date":"2023-12-04T15:03:18","date_gmt":"2023-12-04T22:03:18","guid":{"rendered":"https:\/\/periodicorealidades.com\/?p=3337"},"modified":"2023-12-04T15:03:19","modified_gmt":"2023-12-04T22:03:19","slug":"medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida","status":"publish","type":"post","link":"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/04\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\/","title":{"rendered":"M\u00e9dicos del IMSS retiran tumor &#8216;gigante&#8217; de beb\u00e9 reci\u00e9n nacida"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La tumoraci\u00f3n, m\u00e1s grande que la cabeza de la beb\u00e9, afectaba la parte inferior de su cara y cuello.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Especialistas del Hospital General del Centro M\u00e9dico Nacional (CMN) La Raza del&nbsp;<strong>Instituto Mexicano del Seguro Social<\/strong>&nbsp;(IMSS) realizaron con \u00e9xito una intervenci\u00f3n quir\u00fargica para retirar un teratoma gigante cervicofacial de 20 cent\u00edmetros de di\u00e1metro, que pon\u00eda en riesgo la vida de una reci\u00e9n nacida.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La tumoraci\u00f3n, m\u00e1s grande que la cabeza de la beb\u00e9<\/strong>, afectaba la parte inferior de su cara y cuello, impidiendo funciones b\u00e1sicas como la respiraci\u00f3n y alimentaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La menor, llamada L\u00eda \u2018N\u2019, naci\u00f3 el 4 de noviembre con este raro teratoma de origen embrionario, que hab\u00eda ido creciendo gradualmente desde el momento de su nacimiento. Ante la complejidad de la situaci\u00f3n, fue necesario el trabajo coordinado de los Servicios de Onco-Cirug\u00eda Pedi\u00e1trica y Oncolog\u00eda Pedi\u00e1trica de la Unidad M\u00e9dica de Alta Especialidad (UMAE) Hospital General \u201cDr. Gaudencio Gonz\u00e1lez Garza\u201d del CMN\u00a0<strong>La Raza<\/strong>.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/editorial.aristeguinoticias.com\/wp-content\/uploads\/2023\/12\/medicos-imss-raza-retiran-tumor-gigante-bebe-recien-nacida-041223-2.jpg\"><img decoding=\"async\" src=\"https:\/\/editorial.aristeguinoticias.com\/wp-content\/uploads\/2023\/12\/medicos-imss-raza-retiran-tumor-gigante-bebe-recien-nacida-041223-2-700x438.jpg\" alt=\"\" class=\"wp-image-1346764\"\/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Desde las 26 semanas de gestaci\u00f3n, los ginec\u00f3logos de la UMAE Hospital de Gineco-Obstetricia No. 3 \u201cDr. V\u00edctor Manuel Espinosa de los Reyes S\u00e1nchez\u201d del mismo conjunto hospitalario detectaron la tumoraci\u00f3n, manteniendo una estrecha vigilancia durante el&nbsp;<strong>embarazo<\/strong>&nbsp;para garantizar la salud de la madre y el desarrollo adecuado de la beb\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La doctora Edna Zoraida Rojas Curiel, jefa del Servicio de Onco-Cirug\u00eda Pedi\u00e1trica de la UMAE Hospital General, destac\u00f3 que esta es la primera vez en la historia del CMN La Raza que se atiende una tumoraci\u00f3n cervicofacial de origen embrionario.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La intervenci\u00f3n permiti\u00f3&nbsp;<strong>retirar completamente el tumor<\/strong>, asegurando la funcionalidad respiratoria, alimenticia y est\u00e9tica de la beb\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La especialista explic\u00f3 que, tras el\u00a0<strong>nacimiento de la beb\u00e9<\/strong>, se realizaron diversos estudios, incluyendo una tomograf\u00eda, evaluaci\u00f3n cardiol\u00f3gica y endosc\u00f3pica, para valorar su situaci\u00f3n m\u00e9dica de manera oportuna. La cirug\u00eda fue planeada cuidadosamente para garantizar la permeabilidad de la v\u00eda a\u00e9rea y el \u00e9xito del procedimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El tumor, que representa un caso poco com\u00fan en la regi\u00f3n, fue enviado al Servicio de Patolog\u00eda para un an\u00e1lisis detallado.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta el momento, la beb\u00e9 se encuentra en recuperaci\u00f3n en la Unidad de Cuidados Intensivos Neonatales y su evoluci\u00f3n es adecuada. En caso de ser necesario, se continuar\u00e1 con el\u00a0<strong>tratamiento oncol\u00f3gico<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La madre de la menor, Evelin, expres\u00f3 su agradecimiento al personal del IMSS por su dedicaci\u00f3n y trabajo para mejorar la salud de su hija. La familia espera con ansias el momento en que la beb\u00e9 pueda estar en sus brazos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La tumoraci\u00f3n, m\u00e1s grande que la cabeza de la beb\u00e9, afectaba la parte inferior de su cara y cuello. Especialistas del Hospital General del Centro M\u00e9dico Nacional (CMN) La Raza del&nbsp;Instituto Mexicano del Seguro Social&nbsp;(IMSS) realizaron con \u00e9xito una intervenci\u00f3n quir\u00fargica para retirar un teratoma gigante cervicofacial de 20 cent\u00edmetros de di\u00e1metro, que pon\u00eda en [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-3337","post","type-post","status-publish","format-standard","category-salud"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e9dicos del IMSS retiran tumor &#039;gigante&#039; de beb\u00e9 reci\u00e9n nacida - Peri\u00f3dico Realidades<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/04\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9dicos del IMSS retiran tumor &#039;gigante&#039; de beb\u00e9 reci\u00e9n nacida - Peri\u00f3dico Realidades\" \/>\n<meta property=\"og:description\" content=\"La tumoraci\u00f3n, m\u00e1s grande que la cabeza de la beb\u00e9, afectaba la parte inferior de su cara y cuello. Especialistas del Hospital General del Centro M\u00e9dico Nacional (CMN) La Raza del&nbsp;Instituto Mexicano del Seguro Social&nbsp;(IMSS) realizaron con \u00e9xito una intervenci\u00f3n quir\u00fargica para retirar un teratoma gigante cervicofacial de 20 cent\u00edmetros de di\u00e1metro, que pon\u00eda en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/04\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\/\" \/>\n<meta property=\"og:site_name\" content=\"Peri\u00f3dico Realidades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-04T22:03:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-04T22:03:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/12\/medicos-imss-raza-retiran-tumor-gigante-bebe-recien-nacida-041223-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Arcelia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arcelia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/12\\\/04\\\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/12\\\/04\\\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\\\/\"},\"author\":{\"name\":\"Arcelia\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/ed60e33c6767be45db655d22ad0c15c4\"},\"headline\":\"M\u00e9dicos del IMSS retiran tumor &#8216;gigante&#8217; de beb\u00e9 reci\u00e9n nacida\",\"datePublished\":\"2023-12-04T22:03:18+00:00\",\"dateModified\":\"2023-12-04T22:03:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/12\\\/04\\\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\\\/\"},\"wordCount\":472,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/12\\\/04\\\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/editorial.aristeguinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/medicos-imss-raza-retiran-tumor-gigante-bebe-recien-nacida-041223-2-700x438.jpg\",\"articleSection\":[\"Salud\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/12\\\/04\\\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/12\\\/04\\\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/12\\\/04\\\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\\\/\",\"name\":\"M\u00e9dicos del IMSS retiran tumor 'gigante' de beb\u00e9 reci\u00e9n nacida - Peri\u00f3dico Realidades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/12\\\/04\\\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/12\\\/04\\\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/editorial.aristeguinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/medicos-imss-raza-retiran-tumor-gigante-bebe-recien-nacida-041223-2-700x438.jpg\",\"datePublished\":\"2023-12-04T22:03:18+00:00\",\"dateModified\":\"2023-12-04T22:03:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/12\\\/04\\\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/12\\\/04\\\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/12\\\/04\\\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/editorial.aristeguinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/medicos-imss-raza-retiran-tumor-gigante-bebe-recien-nacida-041223-2-700x438.jpg\",\"contentUrl\":\"https:\\\/\\\/editorial.aristeguinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/medicos-imss-raza-retiran-tumor-gigante-bebe-recien-nacida-041223-2-700x438.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/12\\\/04\\\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/periodicorealidades.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e9dicos del IMSS retiran tumor &#8216;gigante&#8217; de beb\u00e9 reci\u00e9n nacida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"name\":\"Peri\u00f3dico Realidades\",\"description\":\"M\u00e9dio de comunicaci\u00f3n en Nayarit\",\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/periodicorealidades.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\",\"name\":\"Peri\u00f3dico Realidades\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"contentUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"width\":709,\"height\":709,\"caption\":\"Peri\u00f3dico Realidades\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/periodicorealidades.denayarit?mibextid=LQQJ4d\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/ed60e33c6767be45db655d22ad0c15c4\",\"name\":\"Arcelia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g\",\"caption\":\"Arcelia\"},\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/author\\\/editor-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9dicos del IMSS retiran tumor 'gigante' de beb\u00e9 reci\u00e9n nacida - Peri\u00f3dico Realidades","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/04\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\/","og_locale":"es_MX","og_type":"article","og_title":"M\u00e9dicos del IMSS retiran tumor 'gigante' de beb\u00e9 reci\u00e9n nacida - Peri\u00f3dico Realidades","og_description":"La tumoraci\u00f3n, m\u00e1s grande que la cabeza de la beb\u00e9, afectaba la parte inferior de su cara y cuello. Especialistas del Hospital General del Centro M\u00e9dico Nacional (CMN) La Raza del&nbsp;Instituto Mexicano del Seguro Social&nbsp;(IMSS) realizaron con \u00e9xito una intervenci\u00f3n quir\u00fargica para retirar un teratoma gigante cervicofacial de 20 cent\u00edmetros de di\u00e1metro, que pon\u00eda en [&hellip;]","og_url":"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/04\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\/","og_site_name":"Peri\u00f3dico Realidades","article_publisher":"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d","article_published_time":"2023-12-04T22:03:18+00:00","article_modified_time":"2023-12-04T22:03:19+00:00","og_image":[{"width":1200,"height":750,"url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/12\/medicos-imss-raza-retiran-tumor-gigante-bebe-recien-nacida-041223-1.webp","type":"image\/webp"}],"author":"Arcelia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Arcelia","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/04\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\/#article","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/04\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\/"},"author":{"name":"Arcelia","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/ed60e33c6767be45db655d22ad0c15c4"},"headline":"M\u00e9dicos del IMSS retiran tumor &#8216;gigante&#8217; de beb\u00e9 reci\u00e9n nacida","datePublished":"2023-12-04T22:03:18+00:00","dateModified":"2023-12-04T22:03:19+00:00","mainEntityOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/04\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\/"},"wordCount":472,"commentCount":0,"publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/04\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\/#primaryimage"},"thumbnailUrl":"https:\/\/editorial.aristeguinoticias.com\/wp-content\/uploads\/2023\/12\/medicos-imss-raza-retiran-tumor-gigante-bebe-recien-nacida-041223-2-700x438.jpg","articleSection":["Salud"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/periodicorealidades.com\/index.php\/2023\/12\/04\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/04\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\/","url":"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/04\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\/","name":"M\u00e9dicos del IMSS retiran tumor 'gigante' de beb\u00e9 reci\u00e9n nacida - Peri\u00f3dico Realidades","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/04\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\/#primaryimage"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/04\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\/#primaryimage"},"thumbnailUrl":"https:\/\/editorial.aristeguinoticias.com\/wp-content\/uploads\/2023\/12\/medicos-imss-raza-retiran-tumor-gigante-bebe-recien-nacida-041223-2-700x438.jpg","datePublished":"2023-12-04T22:03:18+00:00","dateModified":"2023-12-04T22:03:19+00:00","breadcrumb":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/04\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/periodicorealidades.com\/index.php\/2023\/12\/04\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/04\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\/#primaryimage","url":"https:\/\/editorial.aristeguinoticias.com\/wp-content\/uploads\/2023\/12\/medicos-imss-raza-retiran-tumor-gigante-bebe-recien-nacida-041223-2-700x438.jpg","contentUrl":"https:\/\/editorial.aristeguinoticias.com\/wp-content\/uploads\/2023\/12\/medicos-imss-raza-retiran-tumor-gigante-bebe-recien-nacida-041223-2-700x438.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/04\/medicos-del-imss-retiran-tumor-gigante-de-bebe-recien-nacida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/periodicorealidades.com\/"},{"@type":"ListItem","position":2,"name":"M\u00e9dicos del IMSS retiran tumor &#8216;gigante&#8217; de beb\u00e9 reci\u00e9n nacida"}]},{"@type":"WebSite","@id":"https:\/\/periodicorealidades.com\/#website","url":"https:\/\/periodicorealidades.com\/","name":"Peri\u00f3dico Realidades","description":"M\u00e9dio de comunicaci\u00f3n en Nayarit","publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/periodicorealidades.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/periodicorealidades.com\/#organization","name":"Peri\u00f3dico Realidades","url":"https:\/\/periodicorealidades.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/","url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","contentUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","width":709,"height":709,"caption":"Peri\u00f3dico Realidades"},"image":{"@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d"]},{"@type":"Person","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/ed60e33c6767be45db655d22ad0c15c4","name":"Arcelia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g","caption":"Arcelia"},"url":"https:\/\/periodicorealidades.com\/index.php\/author\/editor-2\/"}]}},"_links":{"self":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/3337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/comments?post=3337"}],"version-history":[{"count":0,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/3337\/revisions"}],"wp:attachment":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/media?parent=3337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/categories?post=3337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/tags?post=3337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}