{"id":3548,"date":"2023-12-05T20:04:49","date_gmt":"2023-12-06T03:04:49","guid":{"rendered":"https:\/\/periodicorealidades.com\/?p=3548"},"modified":"2023-12-05T20:04:50","modified_gmt":"2023-12-06T03:04:50","slug":"el-ataque-a-la-turista-en-jalisco-fue-por-un-tiburon-toro-hembra","status":"publish","type":"post","link":"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/05\/el-ataque-a-la-turista-en-jalisco-fue-por-un-tiburon-toro-hembra\/","title":{"rendered":"El ataque a la turista en Jalisco fue por un tibur\u00f3n Toro hembra"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">AVISO IMPORTANTE<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Derivado del primer hecho acontecido el pasado domingo 3 de diciembre del a\u00f1o en curso en la playa de Melaque, del municipio de Cihuatl\u00e1n, Jalisco en donde lamentablemente una mujer de 26 a\u00f1os de edad perdiera la vida al ser mordida por un tibur\u00f3n de la especie de nombre cient\u00edfico de \u201cTibur\u00f3n toro (Carcharas leucas)\u201d y del segundo suceso ocurrido en la misma playa, en el que un pescador resultara lesionado al ser mordido en el pie por un tibur\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana de Nayarit comparte la siguiente informaci\u00f3n emitida por el experto, el Doctor y Catedr\u00e1tico del CUCSUR UDG Bernab\u00e9 Aguilar Palomino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En primera instancia, la noticia se difundi\u00f3 con la inc\u00f3gnita de que la femenina pudiera haber sido mordida por un cocodrilo o tibur\u00f3n blanco, pero, el doctor manifest\u00f3 que por la naturaleza de la mordida se descart\u00f3 que fuera un Crocodylus acutus y el tibur\u00f3n blanco (Carcharodon carcharias) se ha observado desde Mazatl\u00e1n, Sinaloa. Hac\u00eda el norte en el oc\u00e9ano pacifico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El doctor expuso, que el caso en el cual la femenina se dirigi\u00f3 a un juego de diversiones flotante de 30 X 20 metros de distancia de la playa cuando sucedi\u00f3 el ataque; quiz\u00e1s dicho juego hizo la funci\u00f3n de una DAP (Dispositivos Agregadores de Peces), dichos DAPS son equipos utilizados en la pesca artesanal e industrial que atraen y agrupan a los peces debido a su comportamiento. Naturalmente los peces tienden a agruparse debajo de objetos flotantes en el mar por la sombra que brinda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunado a esta explicaci\u00f3n, se estima que la mordida fatal fue ocasionada por un tibur\u00f3n toro (Carcharias leucas) hembra, misma que probablemente acabara de parir (es una especie viv\u00edpara), esta especie puede medir hasta 3.40 metros y de todos los tiburones es el que tiene la mordida m\u00e1s poderosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, el bi\u00f3logo perteneciente a la Direcci\u00f3n General de Protecci\u00f3n Ciudadana y Bomberos de Nayarit expone que hasta el momento se descarta la presencia de fauna marina que implique riesgo para el humano cerca de las zonas de playa del Estado de Nayarit, sin embargo, los guardavidas adscritos a esta direcci\u00f3n en coordinaci\u00f3n con autoridades federales mantienen monitoreo constante en torno a los tipos de fauna que habitan y\/o visitan la entidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AVISO IMPORTANTE Derivado del primer hecho acontecido el pasado domingo 3 de diciembre del a\u00f1o en curso en la playa de Melaque, del municipio de Cihuatl\u00e1n, Jalisco en donde lamentablemente una mujer de 26 a\u00f1os de edad perdiera la vida al ser mordida por un tibur\u00f3n de la especie de nombre cient\u00edfico de \u201cTibur\u00f3n toro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-3548","post","type-post","status-publish","format-standard","category-policiaca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El ataque a la turista en Jalisco fue por un tibur\u00f3n Toro hembra - Peri\u00f3dico Realidades<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/05\/el-ataque-a-la-turista-en-jalisco-fue-por-un-tiburon-toro-hembra\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El ataque a la turista en Jalisco fue por un tibur\u00f3n Toro hembra - Peri\u00f3dico Realidades\" \/>\n<meta property=\"og:description\" content=\"AVISO IMPORTANTE Derivado del primer hecho acontecido el pasado domingo 3 de diciembre del a\u00f1o en curso en la playa de Melaque, del municipio de Cihuatl\u00e1n, Jalisco en donde lamentablemente una mujer de 26 a\u00f1os de edad perdiera la vida al ser mordida por un tibur\u00f3n de la especie de nombre cient\u00edfico de \u201cTibur\u00f3n toro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/05\/el-ataque-a-la-turista-en-jalisco-fue-por-un-tiburon-toro-hembra\/\" \/>\n<meta property=\"og:site_name\" content=\"Peri\u00f3dico Realidades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-06T03:04:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-06T03:04:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/12\/IMG_0574.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"345\" \/>\n\t<meta property=\"og:image:height\" content=\"237\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/12\\\/05\\\/el-ataque-a-la-turista-en-jalisco-fue-por-un-tiburon-toro-hembra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/12\\\/05\\\/el-ataque-a-la-turista-en-jalisco-fue-por-un-tiburon-toro-hembra\\\/\"},\"author\":{\"name\":\"editor\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/c27da34ee13acaec3162071a3e1c7832\"},\"headline\":\"El ataque a la turista en Jalisco fue por un tibur\u00f3n Toro hembra\",\"datePublished\":\"2023-12-06T03:04:49+00:00\",\"dateModified\":\"2023-12-06T03:04:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/12\\\/05\\\/el-ataque-a-la-turista-en-jalisco-fue-por-un-tiburon-toro-hembra\\\/\"},\"wordCount\":415,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"articleSection\":[\"Policiaca\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/12\\\/05\\\/el-ataque-a-la-turista-en-jalisco-fue-por-un-tiburon-toro-hembra\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/12\\\/05\\\/el-ataque-a-la-turista-en-jalisco-fue-por-un-tiburon-toro-hembra\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/12\\\/05\\\/el-ataque-a-la-turista-en-jalisco-fue-por-un-tiburon-toro-hembra\\\/\",\"name\":\"El ataque a la turista en Jalisco fue por un tibur\u00f3n Toro hembra - Peri\u00f3dico Realidades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\"},\"datePublished\":\"2023-12-06T03:04:49+00:00\",\"dateModified\":\"2023-12-06T03:04:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/12\\\/05\\\/el-ataque-a-la-turista-en-jalisco-fue-por-un-tiburon-toro-hembra\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/12\\\/05\\\/el-ataque-a-la-turista-en-jalisco-fue-por-un-tiburon-toro-hembra\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2023\\\/12\\\/05\\\/el-ataque-a-la-turista-en-jalisco-fue-por-un-tiburon-toro-hembra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/periodicorealidades.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El ataque a la turista en Jalisco fue por un tibur\u00f3n Toro hembra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"name\":\"Peri\u00f3dico Realidades\",\"description\":\"M\u00e9dio de comunicaci\u00f3n en Nayarit\",\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/periodicorealidades.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\",\"name\":\"Peri\u00f3dico Realidades\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"contentUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"width\":709,\"height\":709,\"caption\":\"Peri\u00f3dico Realidades\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/periodicorealidades.denayarit?mibextid=LQQJ4d\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/c27da34ee13acaec3162071a3e1c7832\",\"name\":\"editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dda3c3f59ea25f4b53cd53df977b0b2628039b17268e57c944a79a00e8a56e26?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dda3c3f59ea25f4b53cd53df977b0b2628039b17268e57c944a79a00e8a56e26?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dda3c3f59ea25f4b53cd53df977b0b2628039b17268e57c944a79a00e8a56e26?s=96&d=mm&r=g\",\"caption\":\"editor\"},\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/author\\\/editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El ataque a la turista en Jalisco fue por un tibur\u00f3n Toro hembra - Peri\u00f3dico Realidades","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/05\/el-ataque-a-la-turista-en-jalisco-fue-por-un-tiburon-toro-hembra\/","og_locale":"es_MX","og_type":"article","og_title":"El ataque a la turista en Jalisco fue por un tibur\u00f3n Toro hembra - Peri\u00f3dico Realidades","og_description":"AVISO IMPORTANTE Derivado del primer hecho acontecido el pasado domingo 3 de diciembre del a\u00f1o en curso en la playa de Melaque, del municipio de Cihuatl\u00e1n, Jalisco en donde lamentablemente una mujer de 26 a\u00f1os de edad perdiera la vida al ser mordida por un tibur\u00f3n de la especie de nombre cient\u00edfico de \u201cTibur\u00f3n toro [&hellip;]","og_url":"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/05\/el-ataque-a-la-turista-en-jalisco-fue-por-un-tiburon-toro-hembra\/","og_site_name":"Peri\u00f3dico Realidades","article_publisher":"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d","article_published_time":"2023-12-06T03:04:49+00:00","article_modified_time":"2023-12-06T03:04:50+00:00","og_image":[{"width":345,"height":237,"url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/12\/IMG_0574.jpeg","type":"image\/jpeg"}],"author":"editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/05\/el-ataque-a-la-turista-en-jalisco-fue-por-un-tiburon-toro-hembra\/#article","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/05\/el-ataque-a-la-turista-en-jalisco-fue-por-un-tiburon-toro-hembra\/"},"author":{"name":"editor","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/c27da34ee13acaec3162071a3e1c7832"},"headline":"El ataque a la turista en Jalisco fue por un tibur\u00f3n Toro hembra","datePublished":"2023-12-06T03:04:49+00:00","dateModified":"2023-12-06T03:04:50+00:00","mainEntityOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/05\/el-ataque-a-la-turista-en-jalisco-fue-por-un-tiburon-toro-hembra\/"},"wordCount":415,"commentCount":0,"publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"articleSection":["Policiaca"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/periodicorealidades.com\/index.php\/2023\/12\/05\/el-ataque-a-la-turista-en-jalisco-fue-por-un-tiburon-toro-hembra\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/05\/el-ataque-a-la-turista-en-jalisco-fue-por-un-tiburon-toro-hembra\/","url":"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/05\/el-ataque-a-la-turista-en-jalisco-fue-por-un-tiburon-toro-hembra\/","name":"El ataque a la turista en Jalisco fue por un tibur\u00f3n Toro hembra - Peri\u00f3dico Realidades","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/#website"},"datePublished":"2023-12-06T03:04:49+00:00","dateModified":"2023-12-06T03:04:50+00:00","breadcrumb":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/05\/el-ataque-a-la-turista-en-jalisco-fue-por-un-tiburon-toro-hembra\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/periodicorealidades.com\/index.php\/2023\/12\/05\/el-ataque-a-la-turista-en-jalisco-fue-por-un-tiburon-toro-hembra\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/periodicorealidades.com\/index.php\/2023\/12\/05\/el-ataque-a-la-turista-en-jalisco-fue-por-un-tiburon-toro-hembra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/periodicorealidades.com\/"},{"@type":"ListItem","position":2,"name":"El ataque a la turista en Jalisco fue por un tibur\u00f3n Toro hembra"}]},{"@type":"WebSite","@id":"https:\/\/periodicorealidades.com\/#website","url":"https:\/\/periodicorealidades.com\/","name":"Peri\u00f3dico Realidades","description":"M\u00e9dio de comunicaci\u00f3n en Nayarit","publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/periodicorealidades.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/periodicorealidades.com\/#organization","name":"Peri\u00f3dico Realidades","url":"https:\/\/periodicorealidades.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/","url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","contentUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","width":709,"height":709,"caption":"Peri\u00f3dico Realidades"},"image":{"@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d"]},{"@type":"Person","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/c27da34ee13acaec3162071a3e1c7832","name":"editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/dda3c3f59ea25f4b53cd53df977b0b2628039b17268e57c944a79a00e8a56e26?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dda3c3f59ea25f4b53cd53df977b0b2628039b17268e57c944a79a00e8a56e26?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dda3c3f59ea25f4b53cd53df977b0b2628039b17268e57c944a79a00e8a56e26?s=96&d=mm&r=g","caption":"editor"},"url":"https:\/\/periodicorealidades.com\/index.php\/author\/editor\/"}]}},"_links":{"self":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/3548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/comments?post=3548"}],"version-history":[{"count":0,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/3548\/revisions"}],"wp:attachment":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/media?parent=3548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/categories?post=3548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/tags?post=3548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}