{"id":38123,"date":"2025-02-14T14:56:52","date_gmt":"2025-02-14T21:56:52","guid":{"rendered":"https:\/\/periodicorealidades.com\/?p=38123"},"modified":"2025-02-14T14:56:53","modified_gmt":"2025-02-14T21:56:53","slug":"gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero","status":"publish","type":"post","link":"https:\/\/periodicorealidades.com\/index.php\/2025\/02\/14\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\/","title":{"rendered":"Gobierno da por concluida misi\u00f3n en El Pinabete tras rescatar \u00faltimo cuerpo de minero"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El pasado 6 de febrero, el Gobierno inform\u00f3 del hallazgo de los restos del d\u00e9cimo y \u00faltimo minero atrapado desde agosto de 2022 en &#8220;El Pinabete&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Gobierno mexicano, a trav\u00e9s de diferentes instituciones, dio por concluida este viernes la misi\u00f3n de b\u00fasqueda de mineros en&nbsp;<strong>El Pinabete<\/strong>, en Coahuila, al informar que logr\u00f3 la recuperaci\u00f3n de los restos del d\u00e9cimo y \u00faltimo trabajador que permanec\u00eda en el interior de las galer\u00edas de ese pozo carbon\u00edfero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDe esta forma&nbsp;<strong>se dan por finalizados los trabajos<\/strong>&nbsp;de la etapa de b\u00fasqueda y recuperaci\u00f3n de los mineros de El Pinabete; sin embargo, se continuar\u00e1 trabajando en el regreso del material extra\u00eddo del tajo y la restauraci\u00f3n ecol\u00f3gica del predio\u201d, se apunt\u00f3 en un comunicado conjunto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Precis\u00f3 que a las 10:09 horas se localizaron restos \u00f3seos en la galer\u00eda GSN6 Norte, en la intersecci\u00f3n con el Tiro Vertical 2 (TV-2) y estos&nbsp;<strong>restos ser\u00e1n trasladados al Servicio M\u00e9dico Forense en Saltillo, Coahuila<\/strong>, para su an\u00e1lisis e identificaci\u00f3n, con el prop\u00f3sito de brindar certeza a sus familiares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pasado 6 de febrero, el Gobierno\u00a0<strong>inform\u00f3 del hallazgo de los restos del d\u00e9cimo y \u00faltimo minero<\/strong>\u00a0atrapado desde agosto de 2022 en la mina de carb\u00f3n \u2018El Pinabete\u2019, en Coahuila.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/editorial.aristeguinoticias.com\/wp-content\/uploads\/2025\/02\/1005074_9no-Minero-Rescatado-Pinabete_web.jpg\"><img decoding=\"async\" src=\"https:\/\/editorial.aristeguinoticias.com\/wp-content\/uploads\/2025\/02\/1005074_9no-Minero-Rescatado-Pinabete_web-700x323.jpg\" alt=\"\" class=\"wp-image-1452253\"\/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">El anuncio ocurre 926 d\u00edas despu\u00e9s del&nbsp;<strong>derrumbe del 3 de agosto de 2022<\/strong>, que dej\u00f3 atrapados a 10 mineros, dando inicio a las labores de rescate.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un comunicado se apunt\u00f3 que\u00a0<strong>la recuperaci\u00f3n de los cuerpos fue un trabajo coordinado<\/strong>\u00a0por las instituciones que integran el Comando Unificado de El Pinabete<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cual est\u00e1 integrado por la Comisi\u00f3n Federal de Electricidad (CFE), la Coordinaci\u00f3n Nacional de Protecci\u00f3n Civil (CNPC), la Secretar\u00eda de la Defensa Nacional (Defensa) y la Fiscal\u00eda General del Estado de Coahuila de Zaragoza (FGEC), quienes garantizaron en todo momento la seguridad del equipo de rescate y&nbsp;<strong>el cumplimiento del Protocolo para la Recuperaci\u00f3n de Hallazgos Biol\u00f3gicos<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presidenta Claudia Sheinbaum&nbsp;<strong>se comprometi\u00f3 a cumplir la promesa<\/strong>&nbsp;del expresidente Andr\u00e9s Manuel L\u00f3pez Obrador (2018-2024) de entregar los restos de los mineros atrapados a sus familias.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/editorial.aristeguinoticias.com\/wp-content\/uploads\/2025\/02\/1008252_Sheinbaum-Encuentro-Familiares-Mineros_web.jpg\"><img decoding=\"async\" src=\"https:\/\/editorial.aristeguinoticias.com\/wp-content\/uploads\/2025\/02\/1008252_Sheinbaum-Encuentro-Familiares-Mineros_web-700x467.jpg\" alt=\"\" class=\"wp-image-1452254\"\/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Los primeros dos cuerpos se encontraron el 28 de diciembre de 2023, tras m\u00e1s de 500 d\u00edas del accidente,&nbsp;<strong>cuando \u2018El Pinabete\u2019, en el municipio carbon\u00edfero de Sabinas, de Coahuila<\/strong>, se inund\u00f3 tras un derrumbe de la mina contigua abandonada llamada \u2018Conchas Norte\u2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras el incidente en la mina, que&nbsp;<strong>ha sido se\u00f1alada por no contar con los permisos y regulaciones en la materia<\/strong>, L\u00f3pez Obrador prometi\u00f3 recuperar los cuerpos meses inmediatos despu\u00e9s del derrumbe, pero tiempo despu\u00e9s el mismo mandatario pronostic\u00f3 que el proceso se prolongar\u00eda hasta 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El derrumbe en \u2018El Pinabete\u2019 reactiv\u00f3 la pol\u00e9mica en M\u00e9xico por la actuaci\u00f3n de las mineras en la regi\u00f3n carbon\u00edfera,&nbsp;<strong>donde se han registrado m\u00e1s de 100 muertes<\/strong>&nbsp;de personas dedicadas a la miner\u00eda, seg\u00fan la Familia Pasta de Conchos, que agrupa a familiares de fallecidos en la mina de ese nombre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la mina Pasta de Conchos, el 19 de febrero de 2006, tras un derrumbe,&nbsp;<strong>quedaron atrapados 65 mineros<\/strong>. El pasado 26 de julio el Gobierno mexicano inform\u00f3 de la identificaci\u00f3n del primer cuerpo rescatado en esta mina. (<em>EFE<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 6 de febrero, el Gobierno inform\u00f3 del hallazgo de los restos del d\u00e9cimo y \u00faltimo minero atrapado desde agosto de 2022 en &#8220;El Pinabete&#8221;. El Gobierno mexicano, a trav\u00e9s de diferentes instituciones, dio por concluida este viernes la misi\u00f3n de b\u00fasqueda de mineros en&nbsp;El Pinabete, en Coahuila, al informar que logr\u00f3 la recuperaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-38123","post","type-post","status-publish","format-standard","category-nacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gobierno da por concluida misi\u00f3n en El Pinabete tras rescatar \u00faltimo cuerpo de minero - Peri\u00f3dico Realidades<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/periodicorealidades.com\/index.php\/2025\/02\/14\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobierno da por concluida misi\u00f3n en El Pinabete tras rescatar \u00faltimo cuerpo de minero - Peri\u00f3dico Realidades\" \/>\n<meta property=\"og:description\" content=\"El pasado 6 de febrero, el Gobierno inform\u00f3 del hallazgo de los restos del d\u00e9cimo y \u00faltimo minero atrapado desde agosto de 2022 en &#8220;El Pinabete&#8221;. El Gobierno mexicano, a trav\u00e9s de diferentes instituciones, dio por concluida este viernes la misi\u00f3n de b\u00fasqueda de mineros en&nbsp;El Pinabete, en Coahuila, al informar que logr\u00f3 la recuperaci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/periodicorealidades.com\/index.php\/2025\/02\/14\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\/\" \/>\n<meta property=\"og:site_name\" content=\"Peri\u00f3dico Realidades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-14T21:56:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-14T21:56:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/02\/Gobierno-por-concluida-mision-Pinabete-tras-rescatar-ultimo-cuerpo-minero-14022025.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arcelia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arcelia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/02\\\/14\\\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/02\\\/14\\\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\\\/\"},\"author\":{\"name\":\"Arcelia\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/ed60e33c6767be45db655d22ad0c15c4\"},\"headline\":\"Gobierno da por concluida misi\u00f3n en El Pinabete tras rescatar \u00faltimo cuerpo de minero\",\"datePublished\":\"2025-02-14T21:56:52+00:00\",\"dateModified\":\"2025-02-14T21:56:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/02\\\/14\\\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\\\/\"},\"wordCount\":585,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/02\\\/14\\\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/editorial.aristeguinoticias.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/1005074_9no-Minero-Rescatado-Pinabete_web-700x323.jpg\",\"articleSection\":[\"Nacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/02\\\/14\\\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/02\\\/14\\\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/02\\\/14\\\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\\\/\",\"name\":\"Gobierno da por concluida misi\u00f3n en El Pinabete tras rescatar \u00faltimo cuerpo de minero - Peri\u00f3dico Realidades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/02\\\/14\\\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/02\\\/14\\\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/editorial.aristeguinoticias.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/1005074_9no-Minero-Rescatado-Pinabete_web-700x323.jpg\",\"datePublished\":\"2025-02-14T21:56:52+00:00\",\"dateModified\":\"2025-02-14T21:56:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/02\\\/14\\\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/02\\\/14\\\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/02\\\/14\\\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/editorial.aristeguinoticias.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/1005074_9no-Minero-Rescatado-Pinabete_web-700x323.jpg\",\"contentUrl\":\"https:\\\/\\\/editorial.aristeguinoticias.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/1005074_9no-Minero-Rescatado-Pinabete_web-700x323.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/02\\\/14\\\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/periodicorealidades.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobierno da por concluida misi\u00f3n en El Pinabete tras rescatar \u00faltimo cuerpo de minero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"name\":\"Peri\u00f3dico Realidades\",\"description\":\"M\u00e9dio de comunicaci\u00f3n en Nayarit\",\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/periodicorealidades.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\",\"name\":\"Peri\u00f3dico Realidades\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"contentUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"width\":709,\"height\":709,\"caption\":\"Peri\u00f3dico Realidades\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/periodicorealidades.denayarit?mibextid=LQQJ4d\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/ed60e33c6767be45db655d22ad0c15c4\",\"name\":\"Arcelia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g\",\"caption\":\"Arcelia\"},\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/author\\\/editor-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gobierno da por concluida misi\u00f3n en El Pinabete tras rescatar \u00faltimo cuerpo de minero - Peri\u00f3dico Realidades","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/periodicorealidades.com\/index.php\/2025\/02\/14\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\/","og_locale":"es_MX","og_type":"article","og_title":"Gobierno da por concluida misi\u00f3n en El Pinabete tras rescatar \u00faltimo cuerpo de minero - Peri\u00f3dico Realidades","og_description":"El pasado 6 de febrero, el Gobierno inform\u00f3 del hallazgo de los restos del d\u00e9cimo y \u00faltimo minero atrapado desde agosto de 2022 en &#8220;El Pinabete&#8221;. El Gobierno mexicano, a trav\u00e9s de diferentes instituciones, dio por concluida este viernes la misi\u00f3n de b\u00fasqueda de mineros en&nbsp;El Pinabete, en Coahuila, al informar que logr\u00f3 la recuperaci\u00f3n [&hellip;]","og_url":"https:\/\/periodicorealidades.com\/index.php\/2025\/02\/14\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\/","og_site_name":"Peri\u00f3dico Realidades","article_publisher":"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d","article_published_time":"2025-02-14T21:56:52+00:00","article_modified_time":"2025-02-14T21:56:53+00:00","og_image":[{"width":1200,"height":750,"url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/02\/Gobierno-por-concluida-mision-Pinabete-tras-rescatar-ultimo-cuerpo-minero-14022025.jpeg","type":"image\/jpeg"}],"author":"Arcelia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Arcelia","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/02\/14\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\/#article","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/02\/14\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\/"},"author":{"name":"Arcelia","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/ed60e33c6767be45db655d22ad0c15c4"},"headline":"Gobierno da por concluida misi\u00f3n en El Pinabete tras rescatar \u00faltimo cuerpo de minero","datePublished":"2025-02-14T21:56:52+00:00","dateModified":"2025-02-14T21:56:53+00:00","mainEntityOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/02\/14\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\/"},"wordCount":585,"commentCount":0,"publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/02\/14\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\/#primaryimage"},"thumbnailUrl":"https:\/\/editorial.aristeguinoticias.com\/wp-content\/uploads\/2025\/02\/1005074_9no-Minero-Rescatado-Pinabete_web-700x323.jpg","articleSection":["Nacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/periodicorealidades.com\/index.php\/2025\/02\/14\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/02\/14\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\/","url":"https:\/\/periodicorealidades.com\/index.php\/2025\/02\/14\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\/","name":"Gobierno da por concluida misi\u00f3n en El Pinabete tras rescatar \u00faltimo cuerpo de minero - Peri\u00f3dico Realidades","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/02\/14\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\/#primaryimage"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/02\/14\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\/#primaryimage"},"thumbnailUrl":"https:\/\/editorial.aristeguinoticias.com\/wp-content\/uploads\/2025\/02\/1005074_9no-Minero-Rescatado-Pinabete_web-700x323.jpg","datePublished":"2025-02-14T21:56:52+00:00","dateModified":"2025-02-14T21:56:53+00:00","breadcrumb":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/02\/14\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/periodicorealidades.com\/index.php\/2025\/02\/14\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/02\/14\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\/#primaryimage","url":"https:\/\/editorial.aristeguinoticias.com\/wp-content\/uploads\/2025\/02\/1005074_9no-Minero-Rescatado-Pinabete_web-700x323.jpg","contentUrl":"https:\/\/editorial.aristeguinoticias.com\/wp-content\/uploads\/2025\/02\/1005074_9no-Minero-Rescatado-Pinabete_web-700x323.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/02\/14\/gobierno-da-por-concluida-mision-en-el-pinabete-tras-rescatar-ultimo-cuerpo-de-minero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/periodicorealidades.com\/"},{"@type":"ListItem","position":2,"name":"Gobierno da por concluida misi\u00f3n en El Pinabete tras rescatar \u00faltimo cuerpo de minero"}]},{"@type":"WebSite","@id":"https:\/\/periodicorealidades.com\/#website","url":"https:\/\/periodicorealidades.com\/","name":"Peri\u00f3dico Realidades","description":"M\u00e9dio de comunicaci\u00f3n en Nayarit","publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/periodicorealidades.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/periodicorealidades.com\/#organization","name":"Peri\u00f3dico Realidades","url":"https:\/\/periodicorealidades.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/","url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","contentUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","width":709,"height":709,"caption":"Peri\u00f3dico Realidades"},"image":{"@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d"]},{"@type":"Person","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/ed60e33c6767be45db655d22ad0c15c4","name":"Arcelia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g","caption":"Arcelia"},"url":"https:\/\/periodicorealidades.com\/index.php\/author\/editor-2\/"}]}},"_links":{"self":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/38123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/comments?post=38123"}],"version-history":[{"count":0,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/38123\/revisions"}],"wp:attachment":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/media?parent=38123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/categories?post=38123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/tags?post=38123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}