{"id":40114,"date":"2025-03-13T13:32:49","date_gmt":"2025-03-13T20:32:49","guid":{"rendered":"https:\/\/periodicorealidades.com\/?p=40114"},"modified":"2025-03-13T13:32:49","modified_gmt":"2025-03-13T20:32:49","slug":"eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre","status":"publish","type":"post","link":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/13\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\/","title":{"rendered":"Eclipse Lunar 2025: Tips para Tomar las Mejores Fotos con tu Celular de la Luna de Sangre"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Aqu\u00ed te damos algunos tips para que tomes las mejores fotos del eclipse lunar 2025 y obtengas las mejores im\u00e1genes de la Luna de Sangre<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No te pierdas&nbsp;<strong>eclipse lunar total de 2025&nbsp;<\/strong>que se podr\u00e1 apreciar en&nbsp;<strong>M\u00e9xico&nbsp;<\/strong>a partir de hoy, 13 de marzo y hasta la madrugada del viernes 14; aqu\u00ed te damos algunos&nbsp;<strong>tips&nbsp;<\/strong>para que tomes las&nbsp;<strong>mejores fotograf\u00edas&nbsp;<\/strong>de la&nbsp;<strong>Luna de Sangre<\/strong>, sin lentes ni telescopio.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Datos:\u00a0<\/strong>El\u00a0<strong>eclipse lunar<\/strong>\u00a0ser\u00e1 visible en\u00a0<strong>M\u00e9xico\u00a0<\/strong>a partir de las\u00a0<strong>23:09\u00a0<\/strong>horas del 13 de marzo y hasta las\u00a0<strong>02:47\u00a0<\/strong>horas del viernes 14<\/li>\n\n\n\n<li>Su\u00a0<strong>punto m\u00e1ximo\u00a0<\/strong>ser\u00e1 a las\u00a0<strong>00:59\u00a0<\/strong>hora del centro de M\u00e9xico<\/li>\n\n\n\n<li>Durante el\u00a0<strong>eclipse lunar<\/strong>, la\u00a0<strong>Luna\u00a0<\/strong>se \u2018pintar\u00e1\u2019 de\u00a0<strong>rojo\u00a0<\/strong>porque el Sol, la Tierra y la misma Luna est\u00e1n alineados de manera que el sat\u00e9lite pasa por la sombra completa de nuestro planeta<\/li>\n\n\n\n<li>La\u00a0<strong>Luna\u00a0<\/strong>con estos tintes rojos no se volver\u00e1 a ver as\u00ed hasta\u00a0<strong>2048<\/strong>, seg\u00fan la\u00a0<strong>NASA<\/strong><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfTips para tomar las mejores fotos del eclipse lunar?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El equipo de&nbsp;<strong>N+<\/strong>&nbsp;<strong>Media<\/strong>&nbsp;te explica c\u00f3mo capturar las&nbsp;<strong>mejores fotograf\u00edas&nbsp;<\/strong>del&nbsp;<strong>eclipse lunar&nbsp;<\/strong>de hoy, para esto necesitas los siguientes tres objetos:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Tel\u00e9fono celular<\/li>\n\n\n\n<li>Binoculares<\/li>\n\n\n\n<li>Tripi\u00e9<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfC\u00f3mo tomar las fotos de la Luna de Sangre, paso a paso?<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lo primero que debes hacer es instalar el tripi\u00e9 en un lugar fijo<\/li>\n\n\n\n<li>Coloca tu tel\u00e9fono celular<\/li>\n\n\n\n<li>Pon los binoculares en la c\u00e1mara del tel\u00e9fono<\/li>\n\n\n\n<li>Puedes usar la c\u00e1mara en modo autom\u00e1tico, pero tambi\u00e9n lo puedes intentar en forma manual o pro\u00a0<\/li>\n\n\n\n<li>Enfoca la Luna\u00a0<\/li>\n\n\n\n<li>Si usas el modo pro o manual, usa los siguientes valores:<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>ISO 100-400<\/td><\/tr><tr><td>Velocidad 1\/100<\/td><\/tr><tr><td>Apertura F\/1.8 \u2013 F\/2.8<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Evita el zoom, pero en caso de que quieras usarlo, que sea con los valores predeterminados del tel\u00e9fono, no con los dedos ampliando la pantalla\u00a0<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Pr\u00f3ximos eclipses<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El\u00a0<strong>eclipse lunar<\/strong>\u00a0de este jueves ser\u00e1 el \u00fanico que podremos disfrutar en M\u00e9xico, en 2025<\/li>\n\n\n\n<li>El pr\u00f3ximo\u00a0<strong>eclipse lunar<\/strong>\u00a0que ser\u00e1 visible en M\u00e9xico de forma parcial ocurrir\u00e1 el 3 de marzo de 2026<\/li>\n\n\n\n<li>El siguiente\u00a0<strong>eclipse total de Sol\u00a0<\/strong>ser\u00e1 el 30 de marzo de 2052<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aqu\u00ed te damos algunos tips para que tomes las mejores fotos del eclipse lunar 2025 y obtengas las mejores im\u00e1genes de la Luna de Sangre No te pierdas&nbsp;eclipse lunar total de 2025&nbsp;que se podr\u00e1 apreciar en&nbsp;M\u00e9xico&nbsp;a partir de hoy, 13 de marzo y hasta la madrugada del viernes 14; aqu\u00ed te damos algunos&nbsp;tips&nbsp;para que tomes [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":40115,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-40114","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eclipse Lunar 2025: Tips para Tomar las Mejores Fotos con tu Celular de la Luna de Sangre - Peri\u00f3dico Realidades<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/13\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eclipse Lunar 2025: Tips para Tomar las Mejores Fotos con tu Celular de la Luna de Sangre - Peri\u00f3dico Realidades\" \/>\n<meta property=\"og:description\" content=\"Aqu\u00ed te damos algunos tips para que tomes las mejores fotos del eclipse lunar 2025 y obtengas las mejores im\u00e1genes de la Luna de Sangre No te pierdas&nbsp;eclipse lunar total de 2025&nbsp;que se podr\u00e1 apreciar en&nbsp;M\u00e9xico&nbsp;a partir de hoy, 13 de marzo y hasta la madrugada del viernes 14; aqu\u00ed te damos algunos&nbsp;tips&nbsp;para que tomes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/13\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\/\" \/>\n<meta property=\"og:site_name\" content=\"Peri\u00f3dico Realidades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-13T20:32:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/03\/eclipse-lunar-2025-luna-sangre.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Arcelia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arcelia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/13\\\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/13\\\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\\\/\"},\"author\":{\"name\":\"Arcelia\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/ed60e33c6767be45db655d22ad0c15c4\"},\"headline\":\"Eclipse Lunar 2025: Tips para Tomar las Mejores Fotos con tu Celular de la Luna de Sangre\",\"datePublished\":\"2025-03-13T20:32:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/13\\\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\\\/\"},\"wordCount\":389,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/13\\\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/eclipse-lunar-2025-luna-sangre.webp\",\"articleSection\":[\"Internacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/13\\\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/13\\\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/13\\\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\\\/\",\"name\":\"Eclipse Lunar 2025: Tips para Tomar las Mejores Fotos con tu Celular de la Luna de Sangre - Peri\u00f3dico Realidades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/13\\\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/13\\\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/eclipse-lunar-2025-luna-sangre.webp\",\"datePublished\":\"2025-03-13T20:32:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/13\\\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/13\\\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/13\\\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/eclipse-lunar-2025-luna-sangre.webp\",\"contentUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/eclipse-lunar-2025-luna-sangre.webp\",\"width\":768,\"height\":432},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/13\\\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/periodicorealidades.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eclipse Lunar 2025: Tips para Tomar las Mejores Fotos con tu Celular de la Luna de Sangre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"name\":\"Peri\u00f3dico Realidades\",\"description\":\"M\u00e9dio de comunicaci\u00f3n en Nayarit\",\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/periodicorealidades.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\",\"name\":\"Peri\u00f3dico Realidades\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"contentUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"width\":709,\"height\":709,\"caption\":\"Peri\u00f3dico Realidades\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/periodicorealidades.denayarit?mibextid=LQQJ4d\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/ed60e33c6767be45db655d22ad0c15c4\",\"name\":\"Arcelia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g\",\"caption\":\"Arcelia\"},\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/author\\\/editor-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eclipse Lunar 2025: Tips para Tomar las Mejores Fotos con tu Celular de la Luna de Sangre - Peri\u00f3dico Realidades","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/13\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\/","og_locale":"es_MX","og_type":"article","og_title":"Eclipse Lunar 2025: Tips para Tomar las Mejores Fotos con tu Celular de la Luna de Sangre - Peri\u00f3dico Realidades","og_description":"Aqu\u00ed te damos algunos tips para que tomes las mejores fotos del eclipse lunar 2025 y obtengas las mejores im\u00e1genes de la Luna de Sangre No te pierdas&nbsp;eclipse lunar total de 2025&nbsp;que se podr\u00e1 apreciar en&nbsp;M\u00e9xico&nbsp;a partir de hoy, 13 de marzo y hasta la madrugada del viernes 14; aqu\u00ed te damos algunos&nbsp;tips&nbsp;para que tomes [&hellip;]","og_url":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/13\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\/","og_site_name":"Peri\u00f3dico Realidades","article_publisher":"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d","article_published_time":"2025-03-13T20:32:49+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/03\/eclipse-lunar-2025-luna-sangre.webp","type":"image\/webp"}],"author":"Arcelia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Arcelia","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/13\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\/#article","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/13\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\/"},"author":{"name":"Arcelia","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/ed60e33c6767be45db655d22ad0c15c4"},"headline":"Eclipse Lunar 2025: Tips para Tomar las Mejores Fotos con tu Celular de la Luna de Sangre","datePublished":"2025-03-13T20:32:49+00:00","mainEntityOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/13\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\/"},"wordCount":389,"commentCount":0,"publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/13\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\/#primaryimage"},"thumbnailUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/03\/eclipse-lunar-2025-luna-sangre.webp","articleSection":["Internacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/periodicorealidades.com\/index.php\/2025\/03\/13\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/13\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\/","url":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/13\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\/","name":"Eclipse Lunar 2025: Tips para Tomar las Mejores Fotos con tu Celular de la Luna de Sangre - Peri\u00f3dico Realidades","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/13\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\/#primaryimage"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/13\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\/#primaryimage"},"thumbnailUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/03\/eclipse-lunar-2025-luna-sangre.webp","datePublished":"2025-03-13T20:32:49+00:00","breadcrumb":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/13\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/periodicorealidades.com\/index.php\/2025\/03\/13\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/13\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\/#primaryimage","url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/03\/eclipse-lunar-2025-luna-sangre.webp","contentUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/03\/eclipse-lunar-2025-luna-sangre.webp","width":768,"height":432},{"@type":"BreadcrumbList","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/13\/eclipse-lunar-2025-tips-para-tomar-las-mejores-fotos-con-tu-celular-de-la-luna-de-sangre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/periodicorealidades.com\/"},{"@type":"ListItem","position":2,"name":"Eclipse Lunar 2025: Tips para Tomar las Mejores Fotos con tu Celular de la Luna de Sangre"}]},{"@type":"WebSite","@id":"https:\/\/periodicorealidades.com\/#website","url":"https:\/\/periodicorealidades.com\/","name":"Peri\u00f3dico Realidades","description":"M\u00e9dio de comunicaci\u00f3n en Nayarit","publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/periodicorealidades.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/periodicorealidades.com\/#organization","name":"Peri\u00f3dico Realidades","url":"https:\/\/periodicorealidades.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/","url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","contentUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","width":709,"height":709,"caption":"Peri\u00f3dico Realidades"},"image":{"@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d"]},{"@type":"Person","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/ed60e33c6767be45db655d22ad0c15c4","name":"Arcelia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g","caption":"Arcelia"},"url":"https:\/\/periodicorealidades.com\/index.php\/author\/editor-2\/"}]}},"_links":{"self":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/40114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/comments?post=40114"}],"version-history":[{"count":0,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/40114\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/media\/40115"}],"wp:attachment":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/media?parent=40114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/categories?post=40114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/tags?post=40114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}