{"id":40756,"date":"2025-03-21T12:57:16","date_gmt":"2025-03-21T19:57:16","guid":{"rendered":"https:\/\/periodicorealidades.com\/?p=40756"},"modified":"2025-03-21T12:57:17","modified_gmt":"2025-03-21T19:57:17","slug":"nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars","status":"publish","type":"post","link":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/21\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\/","title":{"rendered":"Nvidia y Disney desarrollan &#8216;Newton&#8217;, un tierno robot basado en Star Wars"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Nvidia anunci\u00f3 una&nbsp;<strong>alianza con Disney Research y Google DeepMind<\/strong>&nbsp;para&nbsp;<strong>desarrollar Newton<\/strong>, un motor de f\u00edsica dise\u00f1ado para mejorar la movilidad y precisi\u00f3n de los robots en entornos del mundo real, inform\u00f3 Jensen Huang, CEO de Nvidia&nbsp;<strong>durante su participaci\u00f3n en GTC 2025<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los primeros usos de Newton ser\u00e1 en los robots de entretenimiento de Disney, como los droides BDX,&nbsp;<strong>inspirados en el universo de Star Wars<\/strong>. Durante la presentaci\u00f3n, un&nbsp;<strong>droide BDX camin\u00f3 en el escenario junto a Huang<\/strong>, demostrando la expresividad y capacidad de movimiento lograda con este sistema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Disney usar\u00e1 Newton para sus parques tem\u00e1ticos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde hace a\u00f1os, Disney ha explorado la idea de&nbsp;<strong>integrar robots en sus parques tem\u00e1ticos<\/strong>, realizando pruebas controladas&nbsp;<strong>en eventos como SXSW 2025<\/strong>. Con el desarrollo de Newton, la compa\u00f1\u00eda parece haber encontrado la soluci\u00f3n para llevar estos droides a sus atracciones a partir del pr\u00f3ximo a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un comunicado de prensa, Kyle Laughlin, vicepresidente senior de Disney Imagineering, destac\u00f3 que la&nbsp;<strong>colaboraci\u00f3n con Nvidia y Google DeepMind<\/strong>&nbsp;ser\u00e1 clave para la pr\u00f3xima generaci\u00f3n de robots de entretenimiento de Disney.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfC\u00f3mo funciona Newton?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Newton est\u00e1 dise\u00f1ado para&nbsp;<strong>mejorar la expresividad y la precisi\u00f3n de los robots<\/strong>&nbsp;en diversas tareas. El motor de f\u00edsica permite simular<strong>&nbsp;c\u00f3mo interact\u00faan los robots con el entorno<\/strong>, un desaf\u00edo fundamental en el desarrollo de sistemas aut\u00f3nomos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan Nvidia, Newton es altamente personalizable y puede programarse para que los robots manipulen objetos deformables, como alimentos, tela o arena. Adem\u00e1s, el motor ser\u00e1 compatible con MuJoCo, el sistema de f\u00edsica desarrollado por Google DeepMind, que permite modelar movimientos rob\u00f3ticos con m\u00faltiples articulaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lanzamiento y compatibilidad con IA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nvidia planea liberar una versi\u00f3n preliminar de c\u00f3digo abierto de Newton a finales de 2025, lo que&nbsp;<strong>permitir\u00e1 a m\u00e1s desarrolladores integrar el sistema<\/strong>&nbsp;en diferentes aplicaciones rob\u00f3ticas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de Newton, en GTC 2025, Nvidia present\u00f3 Groot N1, un modelo de inteligencia artificial dise\u00f1ado para robots humanoides, que les permitir\u00e1 razonar mejor sobre su entorno. Tambi\u00e9n revel\u00f3 su hoja de ruta para el desarrollo de chips de IA de pr\u00f3xima generaci\u00f3n, incluyendo Blackwell Ultra y Rubin, y una nueva l\u00ednea de computadoras personales con IA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con estas innovaciones, Nvidia busca posicionar su tecnolog\u00eda como l\u00edder en el desarrollo de rob\u00f3tica avanzada, mientras que Disney se prepara para revolucionar la experiencia de sus parques tem\u00e1ticos con robots m\u00e1s realistas e interactivos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nvidia anunci\u00f3 una&nbsp;alianza con Disney Research y Google DeepMind&nbsp;para&nbsp;desarrollar Newton, un motor de f\u00edsica dise\u00f1ado para mejorar la movilidad y precisi\u00f3n de los robots en entornos del mundo real, inform\u00f3 Jensen Huang, CEO de Nvidia&nbsp;durante su participaci\u00f3n en GTC 2025. Uno de los primeros usos de Newton ser\u00e1 en los robots de entretenimiento de Disney, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":40757,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-40756","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nvidia y Disney desarrollan &#039;Newton&#039;, un tierno robot basado en Star Wars - Peri\u00f3dico Realidades<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/21\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nvidia y Disney desarrollan &#039;Newton&#039;, un tierno robot basado en Star Wars - Peri\u00f3dico Realidades\" \/>\n<meta property=\"og:description\" content=\"Nvidia anunci\u00f3 una&nbsp;alianza con Disney Research y Google DeepMind&nbsp;para&nbsp;desarrollar Newton, un motor de f\u00edsica dise\u00f1ado para mejorar la movilidad y precisi\u00f3n de los robots en entornos del mundo real, inform\u00f3 Jensen Huang, CEO de Nvidia&nbsp;durante su participaci\u00f3n en GTC 2025. Uno de los primeros usos de Newton ser\u00e1 en los robots de entretenimiento de Disney, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/21\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\/\" \/>\n<meta property=\"og:site_name\" content=\"Peri\u00f3dico Realidades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-21T19:57:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-21T19:57:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/03\/image-67.png\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Luz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/21\\\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/21\\\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\\\/\"},\"author\":{\"name\":\"Luz\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/0553927ea6ee0180215eac70d72ccbc8\"},\"headline\":\"Nvidia y Disney desarrollan &#8216;Newton&#8217;, un tierno robot basado en Star Wars\",\"datePublished\":\"2025-03-21T19:57:16+00:00\",\"dateModified\":\"2025-03-21T19:57:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/21\\\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\\\/\"},\"wordCount\":457,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/21\\\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/image-67.png\",\"articleSection\":[\"Internacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/21\\\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/21\\\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/21\\\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\\\/\",\"name\":\"Nvidia y Disney desarrollan 'Newton', un tierno robot basado en Star Wars - Peri\u00f3dico Realidades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/21\\\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/21\\\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/image-67.png\",\"datePublished\":\"2025-03-21T19:57:16+00:00\",\"dateModified\":\"2025-03-21T19:57:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/21\\\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/21\\\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/21\\\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\\\/#primaryimage\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/image-67.png\",\"contentUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/image-67.png\",\"width\":768,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/03\\\/21\\\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/periodicorealidades.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nvidia y Disney desarrollan &#8216;Newton&#8217;, un tierno robot basado en Star Wars\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"name\":\"Peri\u00f3dico Realidades\",\"description\":\"M\u00e9dio de comunicaci\u00f3n en Nayarit\",\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/periodicorealidades.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\",\"name\":\"Peri\u00f3dico Realidades\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"contentUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"width\":709,\"height\":709,\"caption\":\"Peri\u00f3dico Realidades\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/periodicorealidades.denayarit?mibextid=LQQJ4d\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/0553927ea6ee0180215eac70d72ccbc8\",\"name\":\"Luz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35b1b65794065782e158352e36e89771c6dbd8dfce5b269d691ac7bfadf1a531?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35b1b65794065782e158352e36e89771c6dbd8dfce5b269d691ac7bfadf1a531?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35b1b65794065782e158352e36e89771c6dbd8dfce5b269d691ac7bfadf1a531?s=96&d=mm&r=g\",\"caption\":\"Luz\"},\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/author\\\/editorl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nvidia y Disney desarrollan 'Newton', un tierno robot basado en Star Wars - Peri\u00f3dico Realidades","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/21\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\/","og_locale":"es_MX","og_type":"article","og_title":"Nvidia y Disney desarrollan 'Newton', un tierno robot basado en Star Wars - Peri\u00f3dico Realidades","og_description":"Nvidia anunci\u00f3 una&nbsp;alianza con Disney Research y Google DeepMind&nbsp;para&nbsp;desarrollar Newton, un motor de f\u00edsica dise\u00f1ado para mejorar la movilidad y precisi\u00f3n de los robots en entornos del mundo real, inform\u00f3 Jensen Huang, CEO de Nvidia&nbsp;durante su participaci\u00f3n en GTC 2025. Uno de los primeros usos de Newton ser\u00e1 en los robots de entretenimiento de Disney, [&hellip;]","og_url":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/21\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\/","og_site_name":"Peri\u00f3dico Realidades","article_publisher":"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d","article_published_time":"2025-03-21T19:57:16+00:00","article_modified_time":"2025-03-21T19:57:17+00:00","og_image":[{"width":768,"height":576,"url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/03\/image-67.png","type":"image\/png"}],"author":"Luz","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Luz","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/21\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\/#article","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/21\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\/"},"author":{"name":"Luz","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/0553927ea6ee0180215eac70d72ccbc8"},"headline":"Nvidia y Disney desarrollan &#8216;Newton&#8217;, un tierno robot basado en Star Wars","datePublished":"2025-03-21T19:57:16+00:00","dateModified":"2025-03-21T19:57:17+00:00","mainEntityOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/21\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\/"},"wordCount":457,"commentCount":0,"publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/21\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\/#primaryimage"},"thumbnailUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/03\/image-67.png","articleSection":["Internacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/periodicorealidades.com\/index.php\/2025\/03\/21\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/21\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\/","url":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/21\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\/","name":"Nvidia y Disney desarrollan 'Newton', un tierno robot basado en Star Wars - Peri\u00f3dico Realidades","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/21\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\/#primaryimage"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/21\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\/#primaryimage"},"thumbnailUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/03\/image-67.png","datePublished":"2025-03-21T19:57:16+00:00","dateModified":"2025-03-21T19:57:17+00:00","breadcrumb":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/21\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/periodicorealidades.com\/index.php\/2025\/03\/21\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/21\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\/#primaryimage","url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/03\/image-67.png","contentUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/03\/image-67.png","width":768,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/03\/21\/nvidia-y-disney-desarrollan-newton-un-tierno-robot-basado-en-star-wars\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/periodicorealidades.com\/"},{"@type":"ListItem","position":2,"name":"Nvidia y Disney desarrollan &#8216;Newton&#8217;, un tierno robot basado en Star Wars"}]},{"@type":"WebSite","@id":"https:\/\/periodicorealidades.com\/#website","url":"https:\/\/periodicorealidades.com\/","name":"Peri\u00f3dico Realidades","description":"M\u00e9dio de comunicaci\u00f3n en Nayarit","publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/periodicorealidades.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/periodicorealidades.com\/#organization","name":"Peri\u00f3dico Realidades","url":"https:\/\/periodicorealidades.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/","url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","contentUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","width":709,"height":709,"caption":"Peri\u00f3dico Realidades"},"image":{"@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d"]},{"@type":"Person","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/0553927ea6ee0180215eac70d72ccbc8","name":"Luz","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/35b1b65794065782e158352e36e89771c6dbd8dfce5b269d691ac7bfadf1a531?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/35b1b65794065782e158352e36e89771c6dbd8dfce5b269d691ac7bfadf1a531?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/35b1b65794065782e158352e36e89771c6dbd8dfce5b269d691ac7bfadf1a531?s=96&d=mm&r=g","caption":"Luz"},"url":"https:\/\/periodicorealidades.com\/index.php\/author\/editorl\/"}]}},"_links":{"self":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/40756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/comments?post=40756"}],"version-history":[{"count":0,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/40756\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/media\/40757"}],"wp:attachment":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/media?parent=40756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/categories?post=40756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/tags?post=40756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}