{"id":42625,"date":"2025-04-14T13:31:34","date_gmt":"2025-04-14T20:31:34","guid":{"rendered":"https:\/\/periodicorealidades.com\/?p=42625"},"modified":"2025-04-14T13:31:35","modified_gmt":"2025-04-14T20:31:35","slug":"cruz-azul-vs-leon-en-vivo-horario-y-donde-ver-el-partido-de-la-jornada-16-de-la-liga-mx-2025","status":"publish","type":"post","link":"https:\/\/periodicorealidades.com\/index.php\/2025\/04\/14\/cruz-azul-vs-leon-en-vivo-horario-y-donde-ver-el-partido-de-la-jornada-16-de-la-liga-mx-2025\/","title":{"rendered":"Cruz Azul vs Le\u00f3n, en vivo: Horario y d\u00f3nde ver el partido de la jornada 16 de la Liga MX 2025"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Cruz Azul recibir\u00e1 a James Rodr\u00edguez y el Le\u00f3n en la\u00a0fecha 16 del Clausura 2025<\/strong>. Con un triunfo, los cementeros pasar\u00edan a los Esmeraldas en la tercera posici\u00f3n de la tabla general, y se colocar\u00edan como favoritos para cerrar en casa su serie de cuartos de final en la Liguilla. Sin embargo, los dirigidos por Eduardo Berizzo est\u00e1n conscientes de la importancia de este duelo, y buscar\u00e1n dar la sorpresa en Ciudad Universitaria, luego de una mala racha de resultados.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La M\u00e1quina llega en un mejor momento que los Panzas Verdes. Los de Vicente S\u00e1nchez ligan 12 partidos sin conocer la derrota, y vienen de dominar a los otros tres \u2018grandes\u2019 del f\u00fatbol mexicano. Adem\u00e1s de vencer a Pumas y Chivas en Liga MX,<strong>\u00a0empataron dos duelos ante el Am\u00e9rica y\u00a0los eliminaron de la Copa de Campeones Concacaf con un triunfo por 2-1.\u00a0<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Le\u00f3n ha bajado las revoluciones, luego de un gran inicio de temporada. De sus \u00faltimos cinco partidos de liga han ganado solamente uno, incluyendo<strong>&nbsp;tres derrotas consecutivas ante Santos Necaxa y Pumas, y un empate contra Quer\u00e9taro<\/strong>. La semana pasada, cambiaron su suerte cuando lograron vencer al Puebla por la m\u00ednima, pero la forma sigue sin convencer a sus aficionados.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero no solo el estado de forma favorece a los cementeros, tambi\u00e9n lo hacen sus \u00faltimos resultados ante los Esmeraldas.<strong>\u00a0Cruz Azul ha perdido solo uno de sus \u00faltimos 13 enfrentamientos contra La Fiera;\u00a0aquella derrota fue por la m\u00ednima en el Apertura 2021<\/strong>. Desde entonces, han ganado seis partidos de liga y empatado solo uno.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-cuando-y-donde-se-jugara-el-cruz-azul-vs-leon-de-la-liga-mx-2025\">\u00bfCu\u00e1ndo y d\u00f3nde se jugar\u00e1 el Cruz Azul vs Le\u00f3n de la Liga MX 2025?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El partido de la fecha 16 del Clausura 2025 entre Cruz Azul y Le\u00f3n se jugar\u00e1 este&nbsp;<strong>martes 15 de abril en el Estadio Ol\u00edmpico Universitario.&nbsp;<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-horario-del-partido-cruz-azul-vs-leon-de-la-liga-mx\">Horario del partido Cruz Azul vs Le\u00f3n de la Liga MX<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El silbatazo inicial del partido Cruz Azul vs Le\u00f3n&nbsp;<strong>se dar\u00e1 en punto de las 21:05 horas del centro de M\u00e9xico.<\/strong>&nbsp;A continuaci\u00f3n, otros horarios.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Colombia: 22:05 horas<\/li>\n\n\n\n<li>Argentina: 00:05 horas (del mi\u00e9rcoles 16 de abril)<\/li>\n\n\n\n<li>Estados Unidos Este (ET): 23:05 horas<\/li>\n\n\n\n<li>Estados Unidos Centro (CT): 22:05 horas<\/li>\n\n\n\n<li>Estados Unidos Pac\u00edfico (PT): 20:05 horas<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quien-transmite-el-partido-cruz-azul-vs-leon-y-donde-ver-en-vivo-online-la-liga-mx\">\u00bfQui\u00e9n transmite el partido Cruz Azul vs Le\u00f3n y d\u00f3nde ver en vivo online la Liga MX?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Cruz Azul vs Le\u00f3n, partido de la Jornada 16 de la Liga MX ser\u00e1 transmitido por TUDN, en sus canales de TV de paga y TV abierta, as\u00ed como en la plataforma ViX+ para M\u00e9xico y Estados Unidos. Mientras que&nbsp;<strong>en Claro Sports te llevaremos las acciones en nuestro reconocido minuto a minuto.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-alineaciones-probables-del-cruz-azul-vs-leon\">Alineaciones probables del Cruz Azul vs Le\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cruz Azul<\/strong>: Kevin Mier; Willer Ditta, Erik Lira, Chiquete Orozco; Jorge S\u00e1nchez, Lorenzo Faravelli, Charly Rodr\u00edguez, Rodolfo Rotondi, Andr\u00e9s Monta\u00f1o; Mateusz Bogusz, \u00c1ngel Sep\u00falveda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le\u00f3n<\/strong>: Alfonso Blanco; David Ram\u00edrez, Stiven Barreiro, Paul Bell\u00f3n, Salvador Reyes; Andr\u00e9s Guardado, Nicol\u00e1s Fonseca; James Rodr\u00edguez, Rodrigo Echeverr\u00eda, Stiven Mendoza, Jhonder C\u00e1diz<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-antecedentes-y-ultimos-resultados-del-cruz-azul-vs-leon\">Antecedentes y \u00faltimos resultados del Cruz Azul vs Le\u00f3n<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le\u00f3n 1-2 Cruz Azul | Apertura 2024 | Jornada 7<\/li>\n\n\n\n<li>Le\u00f3n 2-3 Cruz Azul | Clausura 2024 | Jornada 9<\/li>\n\n\n\n<li>Cruz Azul 1-0 Le\u00f3n | Apertura 2023 | Jornada 14<\/li>\n\n\n\n<li>Le\u00f3n 0-0 Cruz Azul | Clausura 2023 | Jornada 14<\/li>\n\n\n\n<li>Cruz Azul 1-0 Le\u00f3n | Apertura 2022 | Play In<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cruz Azul recibir\u00e1 a James Rodr\u00edguez y el Le\u00f3n en la\u00a0fecha 16 del Clausura 2025. Con un triunfo, los cementeros pasar\u00edan a los Esmeraldas en la tercera posici\u00f3n de la tabla general, y se colocar\u00edan como favoritos para cerrar en casa su serie de cuartos de final en la Liguilla. Sin embargo, los dirigidos por [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-42625","post","type-post","status-publish","format-standard","category-sincategoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cruz Azul vs Le\u00f3n, en vivo: Horario y d\u00f3nde ver el partido de la jornada 16 de la Liga MX 2025 - Peri\u00f3dico Realidades<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/periodicorealidades.com\/index.php\/2025\/04\/14\/cruz-azul-vs-leon-en-vivo-horario-y-donde-ver-el-partido-de-la-jornada-16-de-la-liga-mx-2025\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cruz Azul vs Le\u00f3n, en vivo: Horario y d\u00f3nde ver el partido de la jornada 16 de la Liga MX 2025 - Peri\u00f3dico Realidades\" \/>\n<meta property=\"og:description\" content=\"Cruz Azul recibir\u00e1 a James Rodr\u00edguez y el Le\u00f3n en la\u00a0fecha 16 del Clausura 2025. Con un triunfo, los cementeros pasar\u00edan a los Esmeraldas en la tercera posici\u00f3n de la tabla general, y se colocar\u00edan como favoritos para cerrar en casa su serie de cuartos de final en la Liguilla. Sin embargo, los dirigidos por [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/periodicorealidades.com\/index.php\/2025\/04\/14\/cruz-azul-vs-leon-en-vivo-horario-y-donde-ver-el-partido-de-la-jornada-16-de-la-liga-mx-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Peri\u00f3dico Realidades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-14T20:31:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-14T20:31:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/04\/AA1CTzeX.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arcelia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arcelia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/04\\\/14\\\/cruz-azul-vs-leon-en-vivo-horario-y-donde-ver-el-partido-de-la-jornada-16-de-la-liga-mx-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/04\\\/14\\\/cruz-azul-vs-leon-en-vivo-horario-y-donde-ver-el-partido-de-la-jornada-16-de-la-liga-mx-2025\\\/\"},\"author\":{\"name\":\"Arcelia\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/ed60e33c6767be45db655d22ad0c15c4\"},\"headline\":\"Cruz Azul vs Le\u00f3n, en vivo: Horario y d\u00f3nde ver el partido de la jornada 16 de la Liga MX 2025\",\"datePublished\":\"2025-04-14T20:31:34+00:00\",\"dateModified\":\"2025-04-14T20:31:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/04\\\/14\\\/cruz-azul-vs-leon-en-vivo-horario-y-donde-ver-el-partido-de-la-jornada-16-de-la-liga-mx-2025\\\/\"},\"wordCount\":598,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"articleSection\":[\"sincategoria\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/04\\\/14\\\/cruz-azul-vs-leon-en-vivo-horario-y-donde-ver-el-partido-de-la-jornada-16-de-la-liga-mx-2025\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/04\\\/14\\\/cruz-azul-vs-leon-en-vivo-horario-y-donde-ver-el-partido-de-la-jornada-16-de-la-liga-mx-2025\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/04\\\/14\\\/cruz-azul-vs-leon-en-vivo-horario-y-donde-ver-el-partido-de-la-jornada-16-de-la-liga-mx-2025\\\/\",\"name\":\"Cruz Azul vs Le\u00f3n, en vivo: Horario y d\u00f3nde ver el partido de la jornada 16 de la Liga MX 2025 - Peri\u00f3dico Realidades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\"},\"datePublished\":\"2025-04-14T20:31:34+00:00\",\"dateModified\":\"2025-04-14T20:31:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/04\\\/14\\\/cruz-azul-vs-leon-en-vivo-horario-y-donde-ver-el-partido-de-la-jornada-16-de-la-liga-mx-2025\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/04\\\/14\\\/cruz-azul-vs-leon-en-vivo-horario-y-donde-ver-el-partido-de-la-jornada-16-de-la-liga-mx-2025\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/04\\\/14\\\/cruz-azul-vs-leon-en-vivo-horario-y-donde-ver-el-partido-de-la-jornada-16-de-la-liga-mx-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/periodicorealidades.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cruz Azul vs Le\u00f3n, en vivo: Horario y d\u00f3nde ver el partido de la jornada 16 de la Liga MX 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"name\":\"Peri\u00f3dico Realidades\",\"description\":\"M\u00e9dio de comunicaci\u00f3n en Nayarit\",\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/periodicorealidades.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\",\"name\":\"Peri\u00f3dico Realidades\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"contentUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"width\":709,\"height\":709,\"caption\":\"Peri\u00f3dico Realidades\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/periodicorealidades.denayarit?mibextid=LQQJ4d\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/ed60e33c6767be45db655d22ad0c15c4\",\"name\":\"Arcelia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g\",\"caption\":\"Arcelia\"},\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/author\\\/editor-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cruz Azul vs Le\u00f3n, en vivo: Horario y d\u00f3nde ver el partido de la jornada 16 de la Liga MX 2025 - Peri\u00f3dico Realidades","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/periodicorealidades.com\/index.php\/2025\/04\/14\/cruz-azul-vs-leon-en-vivo-horario-y-donde-ver-el-partido-de-la-jornada-16-de-la-liga-mx-2025\/","og_locale":"es_MX","og_type":"article","og_title":"Cruz Azul vs Le\u00f3n, en vivo: Horario y d\u00f3nde ver el partido de la jornada 16 de la Liga MX 2025 - Peri\u00f3dico Realidades","og_description":"Cruz Azul recibir\u00e1 a James Rodr\u00edguez y el Le\u00f3n en la\u00a0fecha 16 del Clausura 2025. Con un triunfo, los cementeros pasar\u00edan a los Esmeraldas en la tercera posici\u00f3n de la tabla general, y se colocar\u00edan como favoritos para cerrar en casa su serie de cuartos de final en la Liguilla. Sin embargo, los dirigidos por [&hellip;]","og_url":"https:\/\/periodicorealidades.com\/index.php\/2025\/04\/14\/cruz-azul-vs-leon-en-vivo-horario-y-donde-ver-el-partido-de-la-jornada-16-de-la-liga-mx-2025\/","og_site_name":"Peri\u00f3dico Realidades","article_publisher":"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d","article_published_time":"2025-04-14T20:31:34+00:00","article_modified_time":"2025-04-14T20:31:35+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/04\/AA1CTzeX.jpg","type":"image\/jpeg"}],"author":"Arcelia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Arcelia","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/04\/14\/cruz-azul-vs-leon-en-vivo-horario-y-donde-ver-el-partido-de-la-jornada-16-de-la-liga-mx-2025\/#article","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/04\/14\/cruz-azul-vs-leon-en-vivo-horario-y-donde-ver-el-partido-de-la-jornada-16-de-la-liga-mx-2025\/"},"author":{"name":"Arcelia","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/ed60e33c6767be45db655d22ad0c15c4"},"headline":"Cruz Azul vs Le\u00f3n, en vivo: Horario y d\u00f3nde ver el partido de la jornada 16 de la Liga MX 2025","datePublished":"2025-04-14T20:31:34+00:00","dateModified":"2025-04-14T20:31:35+00:00","mainEntityOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/04\/14\/cruz-azul-vs-leon-en-vivo-horario-y-donde-ver-el-partido-de-la-jornada-16-de-la-liga-mx-2025\/"},"wordCount":598,"commentCount":0,"publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"articleSection":["sincategoria"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/periodicorealidades.com\/index.php\/2025\/04\/14\/cruz-azul-vs-leon-en-vivo-horario-y-donde-ver-el-partido-de-la-jornada-16-de-la-liga-mx-2025\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/04\/14\/cruz-azul-vs-leon-en-vivo-horario-y-donde-ver-el-partido-de-la-jornada-16-de-la-liga-mx-2025\/","url":"https:\/\/periodicorealidades.com\/index.php\/2025\/04\/14\/cruz-azul-vs-leon-en-vivo-horario-y-donde-ver-el-partido-de-la-jornada-16-de-la-liga-mx-2025\/","name":"Cruz Azul vs Le\u00f3n, en vivo: Horario y d\u00f3nde ver el partido de la jornada 16 de la Liga MX 2025 - Peri\u00f3dico Realidades","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/#website"},"datePublished":"2025-04-14T20:31:34+00:00","dateModified":"2025-04-14T20:31:35+00:00","breadcrumb":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/04\/14\/cruz-azul-vs-leon-en-vivo-horario-y-donde-ver-el-partido-de-la-jornada-16-de-la-liga-mx-2025\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/periodicorealidades.com\/index.php\/2025\/04\/14\/cruz-azul-vs-leon-en-vivo-horario-y-donde-ver-el-partido-de-la-jornada-16-de-la-liga-mx-2025\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/04\/14\/cruz-azul-vs-leon-en-vivo-horario-y-donde-ver-el-partido-de-la-jornada-16-de-la-liga-mx-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/periodicorealidades.com\/"},{"@type":"ListItem","position":2,"name":"Cruz Azul vs Le\u00f3n, en vivo: Horario y d\u00f3nde ver el partido de la jornada 16 de la Liga MX 2025"}]},{"@type":"WebSite","@id":"https:\/\/periodicorealidades.com\/#website","url":"https:\/\/periodicorealidades.com\/","name":"Peri\u00f3dico Realidades","description":"M\u00e9dio de comunicaci\u00f3n en Nayarit","publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/periodicorealidades.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/periodicorealidades.com\/#organization","name":"Peri\u00f3dico Realidades","url":"https:\/\/periodicorealidades.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/","url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","contentUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","width":709,"height":709,"caption":"Peri\u00f3dico Realidades"},"image":{"@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d"]},{"@type":"Person","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/ed60e33c6767be45db655d22ad0c15c4","name":"Arcelia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g","caption":"Arcelia"},"url":"https:\/\/periodicorealidades.com\/index.php\/author\/editor-2\/"}]}},"_links":{"self":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/42625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/comments?post=42625"}],"version-history":[{"count":0,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/42625\/revisions"}],"wp:attachment":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/media?parent=42625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/categories?post=42625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/tags?post=42625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}