{"id":52364,"date":"2025-09-03T14:36:33","date_gmt":"2025-09-03T21:36:33","guid":{"rendered":"https:\/\/periodicorealidades.com\/?p=52364"},"modified":"2025-09-03T14:38:40","modified_gmt":"2025-09-03T21:38:40","slug":"trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2","status":"publish","type":"post","link":"https:\/\/periodicorealidades.com\/index.php\/2025\/09\/03\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\/","title":{"rendered":"Trump afirma que EE.UU. dispar\u00f3 contra barco con drogas proveniente de Venezuela"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El presidente de Estados Unidos, Donald Trump, inform\u00f3 desde la Oficina Oval que el Ej\u00e9rcito estadounidense llev\u00f3 a cabo un ataque contra una embarcaci\u00f3n que transportaba drogas desde Venezuela.&#8221;Lo ver\u00e1n y leer\u00e1n sobre ello&#8221;, declar\u00f3 Trump al anunciar el incidente, asegurando que &#8220;ocurri\u00f3 hace apenas unos momentos&#8221; y que fue informado al respecto por el jefe del Estado Mayor Conjunto, a quien elogi\u00f3 por su desempe\u00f1o. \u201cY hay m\u00e1s de donde sali\u00f3 eso\u201d, advirti\u00f3, en referencia a futuras acciones similares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enmarcando su declaraci\u00f3n en el contexto de su lucha contra el narcotr\u00e1fico, Trump asegur\u00f3 que \u201cuna gran cantidad de drogas ha estado llegando a nuestro pa\u00eds desde hace mucho tiempo\u201d, se\u00f1alando a Venezuela como uno de los principales puntos de origen. \u201cEstas salieron de Venezuela y est\u00e1n saliendo en grandes cantidades. Est\u00e1n saliendo muchas cosas de Venezuela. As\u00ed que las eliminamos, y podr\u00e1n verlo despu\u00e9s de esta reuni\u00f3n\u201d, afirm\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mandatario no ofreci\u00f3 detalles sobre la localizaci\u00f3n exacta del incidente, el tipo de armamento o plataforma militar utilizada, ni mencion\u00f3 si hubo detenciones, decomisos o v\u00edctimas como resultado del ataque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Poco despu\u00e9s, el secretario de Estado, Marco Rubio, confirm\u00f3 el hecho al se\u00f1alar que se trat\u00f3 de &#8220;un ataque letal en el sur del Caribe contra una embarcaci\u00f3n de drogas que hab\u00eda partido de Venezuela&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este evento se suma a la creciente tensi\u00f3n entre Estados Unidos y el r\u00e9gimen venezolano, y refuerza la postura de l\u00ednea dura que Trump mantuvo durante su administraci\u00f3n respecto al narcotr\u00e1fico y la seguridad nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Estados Unidos, Donald Trump, inform\u00f3 desde la Oficina Oval que el Ej\u00e9rcito estadounidense llev\u00f3 a cabo un ataque contra una embarcaci\u00f3n que transportaba drogas desde Venezuela.&#8221;Lo ver\u00e1n y leer\u00e1n sobre ello&#8221;, declar\u00f3 Trump al anunciar el incidente, asegurando que &#8220;ocurri\u00f3 hace apenas unos momentos&#8221; y que fue informado al respecto por el [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":52369,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,1],"tags":[],"class_list":["post-52364","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacional","category-sincategoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trump afirma que EE.UU. dispar\u00f3 contra barco con drogas proveniente de Venezuela - Peri\u00f3dico Realidades<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/periodicorealidades.com\/index.php\/2025\/09\/03\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump afirma que EE.UU. dispar\u00f3 contra barco con drogas proveniente de Venezuela - Peri\u00f3dico Realidades\" \/>\n<meta property=\"og:description\" content=\"El presidente de Estados Unidos, Donald Trump, inform\u00f3 desde la Oficina Oval que el Ej\u00e9rcito estadounidense llev\u00f3 a cabo un ataque contra una embarcaci\u00f3n que transportaba drogas desde Venezuela.&#8221;Lo ver\u00e1n y leer\u00e1n sobre ello&#8221;, declar\u00f3 Trump al anunciar el incidente, asegurando que &#8220;ocurri\u00f3 hace apenas unos momentos&#8221; y que fue informado al respecto por el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/periodicorealidades.com\/index.php\/2025\/09\/03\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Peri\u00f3dico Realidades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-03T21:36:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-03T21:38:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/09\/image-28.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arcelia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arcelia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/09\\\/03\\\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/09\\\/03\\\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\\\/\"},\"author\":{\"name\":\"Arcelia\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/ed60e33c6767be45db655d22ad0c15c4\"},\"headline\":\"Trump afirma que EE.UU. dispar\u00f3 contra barco con drogas proveniente de Venezuela\",\"datePublished\":\"2025-09-03T21:36:33+00:00\",\"dateModified\":\"2025-09-03T21:38:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/09\\\/03\\\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\\\/\"},\"wordCount\":290,\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/09\\\/03\\\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/image-28.png\",\"articleSection\":[\"Internacional\",\"sincategoria\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/09\\\/03\\\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/09\\\/03\\\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\\\/\",\"name\":\"Trump afirma que EE.UU. dispar\u00f3 contra barco con drogas proveniente de Venezuela - Peri\u00f3dico Realidades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/09\\\/03\\\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/09\\\/03\\\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/image-28.png\",\"datePublished\":\"2025-09-03T21:36:33+00:00\",\"dateModified\":\"2025-09-03T21:38:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/09\\\/03\\\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/09\\\/03\\\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/09\\\/03\\\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/image-28.png\",\"contentUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/image-28.png\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/09\\\/03\\\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/periodicorealidades.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump afirma que EE.UU. dispar\u00f3 contra barco con drogas proveniente de Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"name\":\"Peri\u00f3dico Realidades\",\"description\":\"M\u00e9dio de comunicaci\u00f3n en Nayarit\",\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/periodicorealidades.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\",\"name\":\"Peri\u00f3dico Realidades\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"contentUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"width\":709,\"height\":709,\"caption\":\"Peri\u00f3dico Realidades\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/periodicorealidades.denayarit?mibextid=LQQJ4d\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/ed60e33c6767be45db655d22ad0c15c4\",\"name\":\"Arcelia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g\",\"caption\":\"Arcelia\"},\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/author\\\/editor-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump afirma que EE.UU. dispar\u00f3 contra barco con drogas proveniente de Venezuela - Peri\u00f3dico Realidades","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/periodicorealidades.com\/index.php\/2025\/09\/03\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\/","og_locale":"es_MX","og_type":"article","og_title":"Trump afirma que EE.UU. dispar\u00f3 contra barco con drogas proveniente de Venezuela - Peri\u00f3dico Realidades","og_description":"El presidente de Estados Unidos, Donald Trump, inform\u00f3 desde la Oficina Oval que el Ej\u00e9rcito estadounidense llev\u00f3 a cabo un ataque contra una embarcaci\u00f3n que transportaba drogas desde Venezuela.&#8221;Lo ver\u00e1n y leer\u00e1n sobre ello&#8221;, declar\u00f3 Trump al anunciar el incidente, asegurando que &#8220;ocurri\u00f3 hace apenas unos momentos&#8221; y que fue informado al respecto por el [&hellip;]","og_url":"https:\/\/periodicorealidades.com\/index.php\/2025\/09\/03\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\/","og_site_name":"Peri\u00f3dico Realidades","article_publisher":"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d","article_published_time":"2025-09-03T21:36:33+00:00","article_modified_time":"2025-09-03T21:38:40+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/09\/image-28.png","type":"image\/png"}],"author":"Arcelia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Arcelia","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/09\/03\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\/#article","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/09\/03\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\/"},"author":{"name":"Arcelia","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/ed60e33c6767be45db655d22ad0c15c4"},"headline":"Trump afirma que EE.UU. dispar\u00f3 contra barco con drogas proveniente de Venezuela","datePublished":"2025-09-03T21:36:33+00:00","dateModified":"2025-09-03T21:38:40+00:00","mainEntityOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/09\/03\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\/"},"wordCount":290,"publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/09\/03\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\/#primaryimage"},"thumbnailUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/09\/image-28.png","articleSection":["Internacional","sincategoria"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/09\/03\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\/","url":"https:\/\/periodicorealidades.com\/index.php\/2025\/09\/03\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\/","name":"Trump afirma que EE.UU. dispar\u00f3 contra barco con drogas proveniente de Venezuela - Peri\u00f3dico Realidades","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/09\/03\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\/#primaryimage"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/09\/03\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\/#primaryimage"},"thumbnailUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/09\/image-28.png","datePublished":"2025-09-03T21:36:33+00:00","dateModified":"2025-09-03T21:38:40+00:00","breadcrumb":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/09\/03\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/periodicorealidades.com\/index.php\/2025\/09\/03\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/09\/03\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\/#primaryimage","url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/09\/image-28.png","contentUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/09\/image-28.png","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/09\/03\/trump-afirma-que-ee-uu-disparo-contra-barco-con-drogas-proveniente-de-venezuela-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/periodicorealidades.com\/"},{"@type":"ListItem","position":2,"name":"Trump afirma que EE.UU. dispar\u00f3 contra barco con drogas proveniente de Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/periodicorealidades.com\/#website","url":"https:\/\/periodicorealidades.com\/","name":"Peri\u00f3dico Realidades","description":"M\u00e9dio de comunicaci\u00f3n en Nayarit","publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/periodicorealidades.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/periodicorealidades.com\/#organization","name":"Peri\u00f3dico Realidades","url":"https:\/\/periodicorealidades.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/","url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","contentUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","width":709,"height":709,"caption":"Peri\u00f3dico Realidades"},"image":{"@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d"]},{"@type":"Person","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/ed60e33c6767be45db655d22ad0c15c4","name":"Arcelia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g","caption":"Arcelia"},"url":"https:\/\/periodicorealidades.com\/index.php\/author\/editor-2\/"}]}},"_links":{"self":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/52364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/comments?post=52364"}],"version-history":[{"count":0,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/52364\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/media\/52369"}],"wp:attachment":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/media?parent=52364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/categories?post=52364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/tags?post=52364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}