{"id":57035,"date":"2025-11-05T16:09:07","date_gmt":"2025-11-05T23:09:07","guid":{"rendered":"https:\/\/periodicorealidades.com\/?p=57035"},"modified":"2025-11-05T16:09:08","modified_gmt":"2025-11-05T23:09:08","slug":"pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto","status":"publish","type":"post","link":"https:\/\/periodicorealidades.com\/index.php\/2025\/11\/05\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\/","title":{"rendered":"\u00a1Pongan piso! Baterista de Man\u00e1 sufre aparatosa ca\u00edda en pleno concierto"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00a1Volvi\u00f3 a pasar! Durante un concierto reciente de <strong>Man\u00e1<\/strong>, uno de los integrantes de la ic\u00f3nica banda mexicana protagoniz\u00f3 un bochornoso momento sobre el escenario. En esta ocasi\u00f3n, no fue <strong>Fher Olvera<\/strong> quien acapar\u00f3 la atenci\u00f3n por un percance, sino el baterista <strong>\u00c1lex Gonz\u00e1lez<\/strong>, quien termin\u00f3 en el suelo tras una inesperada ca\u00edda en medio del show.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El incidente ocurri\u00f3 mientras el grupo interpretaba el tema <strong>\u201cD\u00e9jame entrar\u201d<\/strong>. En videos que ya circulan en redes sociales, se observa a \u00c1lex subirse con energ\u00eda al banquillo de su bater\u00eda y comenzar a bailar mientras Fher cantaba frente a \u00e9l. Sin embargo, al intentar girar sobre el asiento, perdi\u00f3 el equilibrio y cay\u00f3 directamente sobre los pedestales y platillos de su instrumento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Afortunadamente, todo qued\u00f3 en un susto. Pese al golpe, Gonz\u00e1lez se reincorpor\u00f3 r\u00e1pidamente y continu\u00f3 tocando como si nada hubiera pasado, lo que gener\u00f3 la ovaci\u00f3n del p\u00fablico por su profesionalismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las reacciones en redes sociales no se hicieron esperar. Mientras algunos admiraron su actitud, otros aprovecharon para bromear sobre el incidente:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCuando no es uno es el otro.\u201d<br>\u201cNo se le quit\u00f3 lo payaso, deber\u00eda tener cuidado, ya tiene m\u00e1s de 60 a\u00f1os\u2026\u201d<br>\u201cEllos ya no est\u00e1n en edad para dar show como antes.\u201d<br>\u201cSi no se cae uno de ellos, no es Man\u00e1.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre risas y preocupaci\u00f3n, los fans celebraron que la ca\u00edda no pasara a mayores. Una vez m\u00e1s, Man\u00e1 demuestra que, incluso con los a\u00f1os encima, su energ\u00eda y entrega sobre el escenario siguen siendo inquebrantables.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-tiktok wp-block-embed-tiktok\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"tiktok-embed\" cite=\"https:\/\/www.tiktok.com\/@mercedesrangelofficial\/video\/7568016414838230280\" data-video-id=\"7568016414838230280\" data-embed-from=\"oembed\" style=\"max-width:605px; min-width:325px;\"> <section> <a target=\"_blank\" title=\"@mercedesrangelofficial\" href=\"https:\/\/www.tiktok.com\/@mercedesrangelofficial?refer=embed\">@mercedesrangelofficial<\/a> <p>Caida de Alex de MAN\u00c1 \ud83e\udd7a @Man\u00e1  <a title=\"man\u00e1\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/man%C3%A1?refer=embed\">#man\u00e1<\/a> <a title=\"concierto\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/concierto?refer=embed\">#concierto<\/a> <a title=\"dallas\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/dallas?refer=embed\">#dallas<\/a> <a title=\"caida\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/caida?refer=embed\">#caida<\/a> <a title=\"alex\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/alex?refer=embed\">#alex<\/a> <\/p> <a target=\"_blank\" title=\"\u266c D\u00e9jame Entrar - Man\u00e1\" href=\"https:\/\/www.tiktok.com\/music\/D\u00e9jame-Entrar-6759710912019433474?refer=embed\">\u266c D\u00e9jame Entrar &#8211; Man\u00e1<\/a> <\/section> <\/blockquote> <script async src=\"https:\/\/www.tiktok.com\/embed.js\"><\/script>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Volvi\u00f3 a pasar! Durante un concierto reciente de Man\u00e1, uno de los integrantes de la ic\u00f3nica banda mexicana protagoniz\u00f3 un bochornoso momento sobre el escenario. En esta ocasi\u00f3n, no fue Fher Olvera quien acapar\u00f3 la atenci\u00f3n por un percance, sino el baterista \u00c1lex Gonz\u00e1lez, quien termin\u00f3 en el suelo tras una inesperada ca\u00edda en medio [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":57043,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-57035","post","type-post","status-publish","format-standard","has-post-thumbnail","category-viral"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1Pongan piso! Baterista de Man\u00e1 sufre aparatosa ca\u00edda en pleno concierto - Peri\u00f3dico Realidades<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/periodicorealidades.com\/index.php\/2025\/11\/05\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Pongan piso! Baterista de Man\u00e1 sufre aparatosa ca\u00edda en pleno concierto - Peri\u00f3dico Realidades\" \/>\n<meta property=\"og:description\" content=\"\u00a1Volvi\u00f3 a pasar! Durante un concierto reciente de Man\u00e1, uno de los integrantes de la ic\u00f3nica banda mexicana protagoniz\u00f3 un bochornoso momento sobre el escenario. En esta ocasi\u00f3n, no fue Fher Olvera quien acapar\u00f3 la atenci\u00f3n por un percance, sino el baterista \u00c1lex Gonz\u00e1lez, quien termin\u00f3 en el suelo tras una inesperada ca\u00edda en medio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/periodicorealidades.com\/index.php\/2025\/11\/05\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\/\" \/>\n<meta property=\"og:site_name\" content=\"Peri\u00f3dico Realidades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-05T23:09:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-05T23:09:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/11\/image-72.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"678\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Luz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/11\\\/05\\\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/11\\\/05\\\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\\\/\"},\"author\":{\"name\":\"Luz\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/0553927ea6ee0180215eac70d72ccbc8\"},\"headline\":\"\u00a1Pongan piso! Baterista de Man\u00e1 sufre aparatosa ca\u00edda en pleno concierto\",\"datePublished\":\"2025-11-05T23:09:07+00:00\",\"dateModified\":\"2025-11-05T23:09:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/11\\\/05\\\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\\\/\"},\"wordCount\":331,\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/11\\\/05\\\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/image-72.png\",\"articleSection\":[\"VIRAL\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/11\\\/05\\\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/11\\\/05\\\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\\\/\",\"name\":\"\u00a1Pongan piso! Baterista de Man\u00e1 sufre aparatosa ca\u00edda en pleno concierto - Peri\u00f3dico Realidades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/11\\\/05\\\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/11\\\/05\\\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/image-72.png\",\"datePublished\":\"2025-11-05T23:09:07+00:00\",\"dateModified\":\"2025-11-05T23:09:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/11\\\/05\\\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/11\\\/05\\\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/11\\\/05\\\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/image-72.png\",\"contentUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/image-72.png\",\"width\":1200,\"height\":678},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/11\\\/05\\\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/periodicorealidades.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Pongan piso! Baterista de Man\u00e1 sufre aparatosa ca\u00edda en pleno concierto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"name\":\"Peri\u00f3dico Realidades\",\"description\":\"M\u00e9dio de comunicaci\u00f3n en Nayarit\",\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/periodicorealidades.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\",\"name\":\"Peri\u00f3dico Realidades\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"contentUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"width\":709,\"height\":709,\"caption\":\"Peri\u00f3dico Realidades\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/periodicorealidades.denayarit?mibextid=LQQJ4d\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/0553927ea6ee0180215eac70d72ccbc8\",\"name\":\"Luz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35b1b65794065782e158352e36e89771c6dbd8dfce5b269d691ac7bfadf1a531?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35b1b65794065782e158352e36e89771c6dbd8dfce5b269d691ac7bfadf1a531?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35b1b65794065782e158352e36e89771c6dbd8dfce5b269d691ac7bfadf1a531?s=96&d=mm&r=g\",\"caption\":\"Luz\"},\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/author\\\/editorl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Pongan piso! Baterista de Man\u00e1 sufre aparatosa ca\u00edda en pleno concierto - Peri\u00f3dico Realidades","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/periodicorealidades.com\/index.php\/2025\/11\/05\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\/","og_locale":"es_MX","og_type":"article","og_title":"\u00a1Pongan piso! Baterista de Man\u00e1 sufre aparatosa ca\u00edda en pleno concierto - Peri\u00f3dico Realidades","og_description":"\u00a1Volvi\u00f3 a pasar! Durante un concierto reciente de Man\u00e1, uno de los integrantes de la ic\u00f3nica banda mexicana protagoniz\u00f3 un bochornoso momento sobre el escenario. En esta ocasi\u00f3n, no fue Fher Olvera quien acapar\u00f3 la atenci\u00f3n por un percance, sino el baterista \u00c1lex Gonz\u00e1lez, quien termin\u00f3 en el suelo tras una inesperada ca\u00edda en medio [&hellip;]","og_url":"https:\/\/periodicorealidades.com\/index.php\/2025\/11\/05\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\/","og_site_name":"Peri\u00f3dico Realidades","article_publisher":"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d","article_published_time":"2025-11-05T23:09:07+00:00","article_modified_time":"2025-11-05T23:09:08+00:00","og_image":[{"width":1200,"height":678,"url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/11\/image-72.png","type":"image\/png"}],"author":"Luz","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Luz","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/11\/05\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\/#article","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/11\/05\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\/"},"author":{"name":"Luz","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/0553927ea6ee0180215eac70d72ccbc8"},"headline":"\u00a1Pongan piso! Baterista de Man\u00e1 sufre aparatosa ca\u00edda en pleno concierto","datePublished":"2025-11-05T23:09:07+00:00","dateModified":"2025-11-05T23:09:08+00:00","mainEntityOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/11\/05\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\/"},"wordCount":331,"publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/11\/05\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\/#primaryimage"},"thumbnailUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/11\/image-72.png","articleSection":["VIRAL"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/11\/05\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\/","url":"https:\/\/periodicorealidades.com\/index.php\/2025\/11\/05\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\/","name":"\u00a1Pongan piso! Baterista de Man\u00e1 sufre aparatosa ca\u00edda en pleno concierto - Peri\u00f3dico Realidades","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/11\/05\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\/#primaryimage"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/11\/05\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\/#primaryimage"},"thumbnailUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/11\/image-72.png","datePublished":"2025-11-05T23:09:07+00:00","dateModified":"2025-11-05T23:09:08+00:00","breadcrumb":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/11\/05\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/periodicorealidades.com\/index.php\/2025\/11\/05\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/11\/05\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\/#primaryimage","url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/11\/image-72.png","contentUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/11\/image-72.png","width":1200,"height":678},{"@type":"BreadcrumbList","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/11\/05\/pongan-piso-baterista-de-mana-sufre-aparatosa-caida-en-pleno-concierto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/periodicorealidades.com\/"},{"@type":"ListItem","position":2,"name":"\u00a1Pongan piso! Baterista de Man\u00e1 sufre aparatosa ca\u00edda en pleno concierto"}]},{"@type":"WebSite","@id":"https:\/\/periodicorealidades.com\/#website","url":"https:\/\/periodicorealidades.com\/","name":"Peri\u00f3dico Realidades","description":"M\u00e9dio de comunicaci\u00f3n en Nayarit","publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/periodicorealidades.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/periodicorealidades.com\/#organization","name":"Peri\u00f3dico Realidades","url":"https:\/\/periodicorealidades.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/","url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","contentUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","width":709,"height":709,"caption":"Peri\u00f3dico Realidades"},"image":{"@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d"]},{"@type":"Person","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/0553927ea6ee0180215eac70d72ccbc8","name":"Luz","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/35b1b65794065782e158352e36e89771c6dbd8dfce5b269d691ac7bfadf1a531?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/35b1b65794065782e158352e36e89771c6dbd8dfce5b269d691ac7bfadf1a531?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/35b1b65794065782e158352e36e89771c6dbd8dfce5b269d691ac7bfadf1a531?s=96&d=mm&r=g","caption":"Luz"},"url":"https:\/\/periodicorealidades.com\/index.php\/author\/editorl\/"}]}},"_links":{"self":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/57035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/comments?post=57035"}],"version-history":[{"count":0,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/57035\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/media\/57043"}],"wp:attachment":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/media?parent=57035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/categories?post=57035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/tags?post=57035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}