{"id":59397,"date":"2025-12-08T15:19:07","date_gmt":"2025-12-08T22:19:07","guid":{"rendered":"https:\/\/periodicorealidades.com\/?p=59397"},"modified":"2025-12-08T15:19:08","modified_gmt":"2025-12-08T22:19:08","slug":"asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano","status":"publish","type":"post","link":"https:\/\/periodicorealidades.com\/index.php\/2025\/12\/08\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\/","title":{"rendered":"Asesinan a joven por celebrar pase del Toluca a la Final del futbol mexicano"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La celebraci\u00f3n por el pase del Toluca a la Final del futbol mexicano termin\u00f3 en tragedia para un joven de 21 a\u00f1os en el municipio de Ju\u00e1rez, Nuevo Le\u00f3n. Juan Alberto Ramos, aficionado de los Diablos Rojos, fue asesinado la noche del s\u00e1bado 6 de diciembre luego de festejar y burlarse de la eliminaci\u00f3n de los Rayados de Monterrey, seg\u00fan relataron sus familiares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ese d\u00eda se disputaron las Semifinales del Apertura 2025, en las que Toluca logr\u00f3 imponerse a Monterrey tras ganar 3-2 el duelo de Vuelta y empatar 3-3 en el global. El club escarlata consigui\u00f3 su boleto a la Final gracias a su mejor posici\u00f3n en la Tabla General, al haberse clasificado como l\u00edder del torneo frente al quinto lugar ocupado por los Rayados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras el silbatazo final, Juan Alberto sali\u00f3 de su domicilio ubicado en la calle Urano, en la colonia Los Cometas, para celebrar el triunfo de su equipo. Minutos despu\u00e9s, una detonaci\u00f3n de arma de fuego interrumpi\u00f3 el festejo. Al escuchar el disparo, sus familiares corrieron hacia la calle y lo encontraron herido, por lo que pidieron auxilio a los servicios de emergencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El joven fue trasladado de inmediato al Hospital General de Ju\u00e1rez; sin embargo, pese a los esfuerzos del personal m\u00e9dico, se confirm\u00f3 su fallecimiento horas m\u00e1s tarde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Fiscal\u00eda General del Estado de Nuevo Le\u00f3n abri\u00f3 una carpeta de investigaci\u00f3n para esclarecer el homicidio y dar con el responsable. Hasta el momento, no se cuenta con informaci\u00f3n sobre la identidad del agresor ni su paradero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La celebraci\u00f3n por el pase del Toluca a la Final del futbol mexicano termin\u00f3 en tragedia para un joven de 21 a\u00f1os en el municipio de Ju\u00e1rez, Nuevo Le\u00f3n. Juan Alberto Ramos, aficionado de los Diablos Rojos, fue asesinado la noche del s\u00e1bado 6 de diciembre luego de festejar y burlarse de la eliminaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":59398,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-59397","post","type-post","status-publish","format-standard","has-post-thumbnail","category-policiaca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Asesinan a joven por celebrar pase del Toluca a la Final del futbol mexicano - Peri\u00f3dico Realidades<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/periodicorealidades.com\/index.php\/2025\/12\/08\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Asesinan a joven por celebrar pase del Toluca a la Final del futbol mexicano - Peri\u00f3dico Realidades\" \/>\n<meta property=\"og:description\" content=\"La celebraci\u00f3n por el pase del Toluca a la Final del futbol mexicano termin\u00f3 en tragedia para un joven de 21 a\u00f1os en el municipio de Ju\u00e1rez, Nuevo Le\u00f3n. Juan Alberto Ramos, aficionado de los Diablos Rojos, fue asesinado la noche del s\u00e1bado 6 de diciembre luego de festejar y burlarse de la eliminaci\u00f3n de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/periodicorealidades.com\/index.php\/2025\/12\/08\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\/\" \/>\n<meta property=\"og:site_name\" content=\"Peri\u00f3dico Realidades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-08T22:19:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-08T22:19:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/12\/image-120.png\" \/>\n\t<meta property=\"og:image:width\" content=\"428\" \/>\n\t<meta property=\"og:image:height\" content=\"486\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Luz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/12\\\/08\\\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/12\\\/08\\\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\\\/\"},\"author\":{\"name\":\"Luz\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/0553927ea6ee0180215eac70d72ccbc8\"},\"headline\":\"Asesinan a joven por celebrar pase del Toluca a la Final del futbol mexicano\",\"datePublished\":\"2025-12-08T22:19:07+00:00\",\"dateModified\":\"2025-12-08T22:19:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/12\\\/08\\\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\\\/\"},\"wordCount\":283,\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/12\\\/08\\\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/image-120.png\",\"articleSection\":[\"Policiaca\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/12\\\/08\\\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/12\\\/08\\\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\\\/\",\"name\":\"Asesinan a joven por celebrar pase del Toluca a la Final del futbol mexicano - Peri\u00f3dico Realidades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/12\\\/08\\\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/12\\\/08\\\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/image-120.png\",\"datePublished\":\"2025-12-08T22:19:07+00:00\",\"dateModified\":\"2025-12-08T22:19:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/12\\\/08\\\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/12\\\/08\\\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/12\\\/08\\\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/image-120.png\",\"contentUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/image-120.png\",\"width\":428,\"height\":486},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2025\\\/12\\\/08\\\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/periodicorealidades.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asesinan a joven por celebrar pase del Toluca a la Final del futbol mexicano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"name\":\"Peri\u00f3dico Realidades\",\"description\":\"M\u00e9dio de comunicaci\u00f3n en Nayarit\",\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/periodicorealidades.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\",\"name\":\"Peri\u00f3dico Realidades\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"contentUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"width\":709,\"height\":709,\"caption\":\"Peri\u00f3dico Realidades\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/periodicorealidades.denayarit?mibextid=LQQJ4d\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/0553927ea6ee0180215eac70d72ccbc8\",\"name\":\"Luz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35b1b65794065782e158352e36e89771c6dbd8dfce5b269d691ac7bfadf1a531?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35b1b65794065782e158352e36e89771c6dbd8dfce5b269d691ac7bfadf1a531?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35b1b65794065782e158352e36e89771c6dbd8dfce5b269d691ac7bfadf1a531?s=96&d=mm&r=g\",\"caption\":\"Luz\"},\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/author\\\/editorl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Asesinan a joven por celebrar pase del Toluca a la Final del futbol mexicano - Peri\u00f3dico Realidades","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/periodicorealidades.com\/index.php\/2025\/12\/08\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\/","og_locale":"es_MX","og_type":"article","og_title":"Asesinan a joven por celebrar pase del Toluca a la Final del futbol mexicano - Peri\u00f3dico Realidades","og_description":"La celebraci\u00f3n por el pase del Toluca a la Final del futbol mexicano termin\u00f3 en tragedia para un joven de 21 a\u00f1os en el municipio de Ju\u00e1rez, Nuevo Le\u00f3n. Juan Alberto Ramos, aficionado de los Diablos Rojos, fue asesinado la noche del s\u00e1bado 6 de diciembre luego de festejar y burlarse de la eliminaci\u00f3n de [&hellip;]","og_url":"https:\/\/periodicorealidades.com\/index.php\/2025\/12\/08\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\/","og_site_name":"Peri\u00f3dico Realidades","article_publisher":"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d","article_published_time":"2025-12-08T22:19:07+00:00","article_modified_time":"2025-12-08T22:19:08+00:00","og_image":[{"width":428,"height":486,"url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/12\/image-120.png","type":"image\/png"}],"author":"Luz","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Luz","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/12\/08\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\/#article","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/12\/08\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\/"},"author":{"name":"Luz","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/0553927ea6ee0180215eac70d72ccbc8"},"headline":"Asesinan a joven por celebrar pase del Toluca a la Final del futbol mexicano","datePublished":"2025-12-08T22:19:07+00:00","dateModified":"2025-12-08T22:19:08+00:00","mainEntityOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/12\/08\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\/"},"wordCount":283,"publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/12\/08\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\/#primaryimage"},"thumbnailUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/12\/image-120.png","articleSection":["Policiaca"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/12\/08\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\/","url":"https:\/\/periodicorealidades.com\/index.php\/2025\/12\/08\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\/","name":"Asesinan a joven por celebrar pase del Toluca a la Final del futbol mexicano - Peri\u00f3dico Realidades","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/12\/08\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\/#primaryimage"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/12\/08\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\/#primaryimage"},"thumbnailUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/12\/image-120.png","datePublished":"2025-12-08T22:19:07+00:00","dateModified":"2025-12-08T22:19:08+00:00","breadcrumb":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/12\/08\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/periodicorealidades.com\/index.php\/2025\/12\/08\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/12\/08\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\/#primaryimage","url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/12\/image-120.png","contentUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2025\/12\/image-120.png","width":428,"height":486},{"@type":"BreadcrumbList","@id":"https:\/\/periodicorealidades.com\/index.php\/2025\/12\/08\/asesinan-a-joven-por-celebrar-pase-del-toluca-a-la-final-del-futbol-mexicano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/periodicorealidades.com\/"},{"@type":"ListItem","position":2,"name":"Asesinan a joven por celebrar pase del Toluca a la Final del futbol mexicano"}]},{"@type":"WebSite","@id":"https:\/\/periodicorealidades.com\/#website","url":"https:\/\/periodicorealidades.com\/","name":"Peri\u00f3dico Realidades","description":"M\u00e9dio de comunicaci\u00f3n en Nayarit","publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/periodicorealidades.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/periodicorealidades.com\/#organization","name":"Peri\u00f3dico Realidades","url":"https:\/\/periodicorealidades.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/","url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","contentUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","width":709,"height":709,"caption":"Peri\u00f3dico Realidades"},"image":{"@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d"]},{"@type":"Person","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/0553927ea6ee0180215eac70d72ccbc8","name":"Luz","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/35b1b65794065782e158352e36e89771c6dbd8dfce5b269d691ac7bfadf1a531?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/35b1b65794065782e158352e36e89771c6dbd8dfce5b269d691ac7bfadf1a531?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/35b1b65794065782e158352e36e89771c6dbd8dfce5b269d691ac7bfadf1a531?s=96&d=mm&r=g","caption":"Luz"},"url":"https:\/\/periodicorealidades.com\/index.php\/author\/editorl\/"}]}},"_links":{"self":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/59397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/comments?post=59397"}],"version-history":[{"count":0,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/59397\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/media\/59398"}],"wp:attachment":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/media?parent=59397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/categories?post=59397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/tags?post=59397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}