{"id":65327,"date":"2026-03-12T17:22:50","date_gmt":"2026-03-13T00:22:50","guid":{"rendered":"https:\/\/periodicorealidades.com\/?p=65327"},"modified":"2026-03-12T17:22:50","modified_gmt":"2026-03-13T00:22:50","slug":"nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz","status":"publish","type":"post","link":"https:\/\/periodicorealidades.com\/index.php\/2026\/03\/12\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\/","title":{"rendered":"Nuevo l\u00edder supremo de Ir\u00e1n desaf\u00eda a Estados Unidos y pide cerrar el Estrecho de Ormuz"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El nuevo l\u00edder supremo de Ir\u00e1n, Mojtaba Jamene\u00ed, lanz\u00f3 un mensaje desafiante hacia Estados Unidos en su primer pronunciamiento oficial tras asumir el cargo, este jueves 12 de marzo de 2026. Durante el mensaje, pidi\u00f3 mantener cerrado el estrat\u00e9gico Estrecho de Ormuz y advirti\u00f3 que las bases militares estadounidenses en Oriente Medio ser\u00e1n atacadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un comunicado transmitido por la televisi\u00f3n estatal iran\u00ed, Jamene\u00ed asegur\u00f3 que \u201cel estrecho de Ormuz debe permanecer cerrado\u201d. Actualmente, el tr\u00e1fico mar\u00edtimo en esta zona \u2014por donde transita cerca del 20 % del petr\u00f3leo mundial\u2014 se encuentra pr\u00e1cticamente detenido debido a los ataques iran\u00edes contra buques desde el inicio de la guerra iniciada el 28 de febrero por Estados Unidos e Israel contra la Rep\u00fablica Isl\u00e1mica.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"275\" height=\"183\" src=\"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/03\/image-167.png\" alt=\"\" class=\"wp-image-65330\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El nuevo dirigente, hijo del fallecido l\u00edder supremo Al\u00ed Jamene\u00ed, advirti\u00f3 que las bases militares estadounidenses desplegadas en la regi\u00f3n ser\u00e1n \u201cinevitablemente\u201d atacadas. Asimismo, pidi\u00f3 a los pa\u00edses vecinos que albergan estas instalaciones que reconsideren su presencia y \u201ccierren esas bases lo antes posible\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jamene\u00ed tambi\u00e9n afirm\u00f3 que Ir\u00e1n busca mantener relaciones \u201cc\u00e1lidas y constructivas\u201d con los pa\u00edses vecinos, y asegur\u00f3 que los ataques registrados en algunos de esos territorios estaban dirigidos \u00fanicamente a instalaciones militares de Estados Unidos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"631\" src=\"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/03\/image-166-1024x631.png\" alt=\"\" class=\"wp-image-65329\" srcset=\"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/03\/image-166-1024x631.png 1024w, https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/03\/image-166-300x185.png 300w, https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/03\/image-166-768x474.png 768w, https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/03\/image-166-696x429.png 696w, https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/03\/image-166-1068x659.png 1068w, https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/03\/image-166-356x220.png 356w, https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/03\/image-166.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El l\u00edder iran\u00ed fue elegido el domingo por la Asamblea de Expertos, convirti\u00e9ndose en el tercer l\u00edder supremo en los 47 a\u00f1os de la Rep\u00fablica Isl\u00e1mica, tras Ruhol\u00e1 Jomein\u00ed y su padre, Al\u00ed Jamene\u00ed, quien muri\u00f3 durante los primeros ataques de Estados Unidos e Israel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan reportes del diario The New York Times, Jamene\u00ed habr\u00eda resultado herido en las piernas durante los bombardeos, aunque esta informaci\u00f3n fue negada por autoridades iran\u00edes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante su mensaje, el nuevo l\u00edder prometi\u00f3 vengar la muerte de las v\u00edctimas del conflicto, incluido el ataque contra un colegio en el sur de Ir\u00e1n que dej\u00f3 168 personas fallecidas. \u201cNo renunciaremos a vengar la sangre de los m\u00e1rtires\u201d, afirm\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, el presidente de Estados Unidos, Donald Trump, declar\u00f3 que frenar el programa nuclear iran\u00ed es m\u00e1s importante que controlar los precios del petr\u00f3leo. A trav\u00e9s de su red social Truth Social, se\u00f1al\u00f3 que impedir que Ir\u00e1n obtenga armas nucleares es fundamental para evitar que el pa\u00eds \u201cdestruya Oriente Medio e incluso el mundo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El nuevo l\u00edder supremo de Ir\u00e1n, Mojtaba Jamene\u00ed, lanz\u00f3 un mensaje desafiante hacia Estados Unidos en su primer pronunciamiento oficial tras asumir el cargo, este jueves 12 de marzo de 2026. Durante el mensaje, pidi\u00f3 mantener cerrado el estrat\u00e9gico Estrecho de Ormuz y advirti\u00f3 que las bases militares estadounidenses en Oriente Medio ser\u00e1n atacadas. En [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":65328,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-65327","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuevo l\u00edder supremo de Ir\u00e1n desaf\u00eda a Estados Unidos y pide cerrar el Estrecho de Ormuz - Peri\u00f3dico Realidades<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/periodicorealidades.com\/index.php\/2026\/03\/12\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuevo l\u00edder supremo de Ir\u00e1n desaf\u00eda a Estados Unidos y pide cerrar el Estrecho de Ormuz - Peri\u00f3dico Realidades\" \/>\n<meta property=\"og:description\" content=\"El nuevo l\u00edder supremo de Ir\u00e1n, Mojtaba Jamene\u00ed, lanz\u00f3 un mensaje desafiante hacia Estados Unidos en su primer pronunciamiento oficial tras asumir el cargo, este jueves 12 de marzo de 2026. Durante el mensaje, pidi\u00f3 mantener cerrado el estrat\u00e9gico Estrecho de Ormuz y advirti\u00f3 que las bases militares estadounidenses en Oriente Medio ser\u00e1n atacadas. En [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/periodicorealidades.com\/index.php\/2026\/03\/12\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\/\" \/>\n<meta property=\"og:site_name\" content=\"Peri\u00f3dico Realidades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-13T00:22:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/03\/image-165.png\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arcelia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arcelia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/03\\\/12\\\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/03\\\/12\\\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\\\/\"},\"author\":{\"name\":\"Arcelia\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/ed60e33c6767be45db655d22ad0c15c4\"},\"headline\":\"Nuevo l\u00edder supremo de Ir\u00e1n desaf\u00eda a Estados Unidos y pide cerrar el Estrecho de Ormuz\",\"datePublished\":\"2026-03-13T00:22:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/03\\\/12\\\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\\\/\"},\"wordCount\":420,\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/03\\\/12\\\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/image-165.png\",\"articleSection\":[\"Internacional\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/03\\\/12\\\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/03\\\/12\\\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\\\/\",\"name\":\"Nuevo l\u00edder supremo de Ir\u00e1n desaf\u00eda a Estados Unidos y pide cerrar el Estrecho de Ormuz - Peri\u00f3dico Realidades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/03\\\/12\\\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/03\\\/12\\\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/image-165.png\",\"datePublished\":\"2026-03-13T00:22:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/03\\\/12\\\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/03\\\/12\\\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/03\\\/12\\\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/image-165.png\",\"contentUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/image-165.png\",\"width\":640,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/03\\\/12\\\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/periodicorealidades.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuevo l\u00edder supremo de Ir\u00e1n desaf\u00eda a Estados Unidos y pide cerrar el Estrecho de Ormuz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"name\":\"Peri\u00f3dico Realidades\",\"description\":\"M\u00e9dio de comunicaci\u00f3n en Nayarit\",\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/periodicorealidades.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\",\"name\":\"Peri\u00f3dico Realidades\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"contentUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"width\":709,\"height\":709,\"caption\":\"Peri\u00f3dico Realidades\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/periodicorealidades.denayarit?mibextid=LQQJ4d\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/ed60e33c6767be45db655d22ad0c15c4\",\"name\":\"Arcelia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g\",\"caption\":\"Arcelia\"},\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/author\\\/editor-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuevo l\u00edder supremo de Ir\u00e1n desaf\u00eda a Estados Unidos y pide cerrar el Estrecho de Ormuz - Peri\u00f3dico Realidades","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/periodicorealidades.com\/index.php\/2026\/03\/12\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\/","og_locale":"es_MX","og_type":"article","og_title":"Nuevo l\u00edder supremo de Ir\u00e1n desaf\u00eda a Estados Unidos y pide cerrar el Estrecho de Ormuz - Peri\u00f3dico Realidades","og_description":"El nuevo l\u00edder supremo de Ir\u00e1n, Mojtaba Jamene\u00ed, lanz\u00f3 un mensaje desafiante hacia Estados Unidos en su primer pronunciamiento oficial tras asumir el cargo, este jueves 12 de marzo de 2026. Durante el mensaje, pidi\u00f3 mantener cerrado el estrat\u00e9gico Estrecho de Ormuz y advirti\u00f3 que las bases militares estadounidenses en Oriente Medio ser\u00e1n atacadas. En [&hellip;]","og_url":"https:\/\/periodicorealidades.com\/index.php\/2026\/03\/12\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\/","og_site_name":"Peri\u00f3dico Realidades","article_publisher":"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d","article_published_time":"2026-03-13T00:22:50+00:00","og_image":[{"width":640,"height":420,"url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/03\/image-165.png","type":"image\/png"}],"author":"Arcelia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Arcelia","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/03\/12\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\/#article","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/03\/12\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\/"},"author":{"name":"Arcelia","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/ed60e33c6767be45db655d22ad0c15c4"},"headline":"Nuevo l\u00edder supremo de Ir\u00e1n desaf\u00eda a Estados Unidos y pide cerrar el Estrecho de Ormuz","datePublished":"2026-03-13T00:22:50+00:00","mainEntityOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/03\/12\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\/"},"wordCount":420,"publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/03\/12\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\/#primaryimage"},"thumbnailUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/03\/image-165.png","articleSection":["Internacional"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/03\/12\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\/","url":"https:\/\/periodicorealidades.com\/index.php\/2026\/03\/12\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\/","name":"Nuevo l\u00edder supremo de Ir\u00e1n desaf\u00eda a Estados Unidos y pide cerrar el Estrecho de Ormuz - Peri\u00f3dico Realidades","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/03\/12\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\/#primaryimage"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/03\/12\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\/#primaryimage"},"thumbnailUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/03\/image-165.png","datePublished":"2026-03-13T00:22:50+00:00","breadcrumb":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/03\/12\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/periodicorealidades.com\/index.php\/2026\/03\/12\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/03\/12\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\/#primaryimage","url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/03\/image-165.png","contentUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/03\/image-165.png","width":640,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/03\/12\/nuevo-lider-supremo-de-iran-desafia-a-estados-unidos-y-pide-cerrar-el-estrecho-de-ormuz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/periodicorealidades.com\/"},{"@type":"ListItem","position":2,"name":"Nuevo l\u00edder supremo de Ir\u00e1n desaf\u00eda a Estados Unidos y pide cerrar el Estrecho de Ormuz"}]},{"@type":"WebSite","@id":"https:\/\/periodicorealidades.com\/#website","url":"https:\/\/periodicorealidades.com\/","name":"Peri\u00f3dico Realidades","description":"M\u00e9dio de comunicaci\u00f3n en Nayarit","publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/periodicorealidades.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/periodicorealidades.com\/#organization","name":"Peri\u00f3dico Realidades","url":"https:\/\/periodicorealidades.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/","url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","contentUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","width":709,"height":709,"caption":"Peri\u00f3dico Realidades"},"image":{"@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d"]},{"@type":"Person","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/ed60e33c6767be45db655d22ad0c15c4","name":"Arcelia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/36cdbbe591db4ecc4985aac5ab27b8093cf6488d3b664974f0cda2e38368b10d?s=96&d=mm&r=g","caption":"Arcelia"},"url":"https:\/\/periodicorealidades.com\/index.php\/author\/editor-2\/"}]}},"_links":{"self":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/65327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/comments?post=65327"}],"version-history":[{"count":0,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/65327\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/media\/65328"}],"wp:attachment":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/media?parent=65327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/categories?post=65327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/tags?post=65327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}