{"id":69802,"date":"2026-05-17T22:57:03","date_gmt":"2026-05-18T05:57:03","guid":{"rendered":"https:\/\/periodicorealidades.com\/?p=69802"},"modified":"2026-05-17T22:57:03","modified_gmt":"2026-05-18T05:57:03","slug":"acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo","status":"publish","type":"post","link":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/17\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\/","title":{"rendered":"Acuerdo hist\u00f3rico Xi- Trump que se sentir\u00e1 en todo el mundo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Casa Blanca ha compartido este domingo los resultados de la cumbre entre Donald Trump y su par chino Xi Jinping, que se celebr\u00f3 en Pek\u00edn entre el 13 y el 15 de mayo. Los presidentes llegaron a un consenso sobre varios asuntos que &#8220;fomentar\u00e1 la estabilidad y confianza para los negocios y consumidores en todo el mundo&#8221;, se\u00f1al\u00f3 en un comunicado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comercio e inversiones<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por: Agencias<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Internacional, lunes, 18 de mayo del 2026.- Trump y Xi establecieron 2 nuevas instituciones para optimizar la relaci\u00f3n econ\u00f3mica bilateral:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp; la Junta de Comercio<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp; la Junta de Inversiones<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La primera facilitar\u00e1 para los gobiernos de ambas naciones la gesti\u00f3n del comercio bilateral de bienes no sensibles, mientras que la segunda &#8220;proporcionar\u00e1 un foro entre gobiernos para abordar cuestiones relacionadas con la inversi\u00f3n&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Casa Blanca califica la fundaci\u00f3n de las instituciones como &#8220;una piedra angular&#8221; del hist\u00f3rico acuerdo entre China y EE.UU. Tierras raras, Boeing y agricultura<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otros acuerdos tratan de un &#8220;amplio paquete de compromisos que impulsar\u00e1 la creaci\u00f3n de empleos bien remunerados en EE.UU. y abrir\u00e1 nuevos mercados para los productos estadounidenses&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tierras raras<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">China &#8220;abordar\u00e1 las preocupaciones de EE.UU. respecto a la escasez en la cadena de suministro relacionada con las tierras raras y otros minerales cr\u00edticos, incluidos el itrio, el escandio, el neodimio y el indio&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n &#8220;abordar\u00e1 las preocupaciones de EE.UU. respecto a las prohibiciones o restricciones sobre la venta de equipos y tecnolog\u00edas de producci\u00f3n y procesamiento de tierras raras&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Casa Blanca ha compartido este domingo los resultados de la cumbre entre Donald Trump y su par chino Xi Jinping, que se celebr\u00f3 en Pek\u00edn entre el 13 y el 15 de mayo. Los presidentes llegaron a un consenso sobre varios asuntos que &#8220;fomentar\u00e1 la estabilidad y confianza para los negocios y consumidores en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":69530,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,4],"tags":[],"class_list":["post-69802","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacional","category-principal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acuerdo hist\u00f3rico Xi- Trump que se sentir\u00e1 en todo el mundo - Peri\u00f3dico Realidades<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/17\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acuerdo hist\u00f3rico Xi- Trump que se sentir\u00e1 en todo el mundo - Peri\u00f3dico Realidades\" \/>\n<meta property=\"og:description\" content=\"La Casa Blanca ha compartido este domingo los resultados de la cumbre entre Donald Trump y su par chino Xi Jinping, que se celebr\u00f3 en Pek\u00edn entre el 13 y el 15 de mayo. Los presidentes llegaron a un consenso sobre varios asuntos que &#8220;fomentar\u00e1 la estabilidad y confianza para los negocios y consumidores en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/17\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\/\" \/>\n<meta property=\"og:site_name\" content=\"Peri\u00f3dico Realidades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-18T05:57:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/05\/TRump-y-xe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"992\" \/>\n\t<meta property=\"og:image:height\" content=\"661\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/05\\\/17\\\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/05\\\/17\\\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\\\/\"},\"author\":{\"name\":\"editor\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/c27da34ee13acaec3162071a3e1c7832\"},\"headline\":\"Acuerdo hist\u00f3rico Xi- Trump que se sentir\u00e1 en todo el mundo\",\"datePublished\":\"2026-05-18T05:57:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/05\\\/17\\\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\\\/\"},\"wordCount\":272,\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/05\\\/17\\\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/TRump-y-xe.jpg\",\"articleSection\":[\"Internacional\",\"Principal\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/05\\\/17\\\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/05\\\/17\\\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\\\/\",\"name\":\"Acuerdo hist\u00f3rico Xi- Trump que se sentir\u00e1 en todo el mundo - Peri\u00f3dico Realidades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/05\\\/17\\\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/05\\\/17\\\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/TRump-y-xe.jpg\",\"datePublished\":\"2026-05-18T05:57:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/05\\\/17\\\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/05\\\/17\\\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/05\\\/17\\\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/TRump-y-xe.jpg\",\"contentUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/TRump-y-xe.jpg\",\"width\":992,\"height\":661},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/05\\\/17\\\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/periodicorealidades.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acuerdo hist\u00f3rico Xi- Trump que se sentir\u00e1 en todo el mundo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"name\":\"Peri\u00f3dico Realidades\",\"description\":\"M\u00e9dio de comunicaci\u00f3n en Nayarit\",\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/periodicorealidades.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\",\"name\":\"Peri\u00f3dico Realidades\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"contentUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"width\":709,\"height\":709,\"caption\":\"Peri\u00f3dico Realidades\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/periodicorealidades.denayarit?mibextid=LQQJ4d\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/c27da34ee13acaec3162071a3e1c7832\",\"name\":\"editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dda3c3f59ea25f4b53cd53df977b0b2628039b17268e57c944a79a00e8a56e26?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dda3c3f59ea25f4b53cd53df977b0b2628039b17268e57c944a79a00e8a56e26?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dda3c3f59ea25f4b53cd53df977b0b2628039b17268e57c944a79a00e8a56e26?s=96&d=mm&r=g\",\"caption\":\"editor\"},\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/author\\\/editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acuerdo hist\u00f3rico Xi- Trump que se sentir\u00e1 en todo el mundo - Peri\u00f3dico Realidades","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/17\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\/","og_locale":"es_MX","og_type":"article","og_title":"Acuerdo hist\u00f3rico Xi- Trump que se sentir\u00e1 en todo el mundo - Peri\u00f3dico Realidades","og_description":"La Casa Blanca ha compartido este domingo los resultados de la cumbre entre Donald Trump y su par chino Xi Jinping, que se celebr\u00f3 en Pek\u00edn entre el 13 y el 15 de mayo. Los presidentes llegaron a un consenso sobre varios asuntos que &#8220;fomentar\u00e1 la estabilidad y confianza para los negocios y consumidores en [&hellip;]","og_url":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/17\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\/","og_site_name":"Peri\u00f3dico Realidades","article_publisher":"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d","article_published_time":"2026-05-18T05:57:03+00:00","og_image":[{"width":992,"height":661,"url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/05\/TRump-y-xe.jpg","type":"image\/jpeg"}],"author":"editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/17\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\/#article","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/17\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\/"},"author":{"name":"editor","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/c27da34ee13acaec3162071a3e1c7832"},"headline":"Acuerdo hist\u00f3rico Xi- Trump que se sentir\u00e1 en todo el mundo","datePublished":"2026-05-18T05:57:03+00:00","mainEntityOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/17\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\/"},"wordCount":272,"publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/17\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/05\/TRump-y-xe.jpg","articleSection":["Internacional","Principal"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/17\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\/","url":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/17\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\/","name":"Acuerdo hist\u00f3rico Xi- Trump que se sentir\u00e1 en todo el mundo - Peri\u00f3dico Realidades","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/17\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\/#primaryimage"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/17\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/05\/TRump-y-xe.jpg","datePublished":"2026-05-18T05:57:03+00:00","breadcrumb":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/17\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/periodicorealidades.com\/index.php\/2026\/05\/17\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/17\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\/#primaryimage","url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/05\/TRump-y-xe.jpg","contentUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/05\/TRump-y-xe.jpg","width":992,"height":661},{"@type":"BreadcrumbList","@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/17\/acuerdo-historico-xi-trump-que-se-sentira-en-todo-el-mundo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/periodicorealidades.com\/"},{"@type":"ListItem","position":2,"name":"Acuerdo hist\u00f3rico Xi- Trump que se sentir\u00e1 en todo el mundo"}]},{"@type":"WebSite","@id":"https:\/\/periodicorealidades.com\/#website","url":"https:\/\/periodicorealidades.com\/","name":"Peri\u00f3dico Realidades","description":"M\u00e9dio de comunicaci\u00f3n en Nayarit","publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/periodicorealidades.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/periodicorealidades.com\/#organization","name":"Peri\u00f3dico Realidades","url":"https:\/\/periodicorealidades.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/","url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","contentUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","width":709,"height":709,"caption":"Peri\u00f3dico Realidades"},"image":{"@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d"]},{"@type":"Person","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/c27da34ee13acaec3162071a3e1c7832","name":"editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/dda3c3f59ea25f4b53cd53df977b0b2628039b17268e57c944a79a00e8a56e26?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dda3c3f59ea25f4b53cd53df977b0b2628039b17268e57c944a79a00e8a56e26?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dda3c3f59ea25f4b53cd53df977b0b2628039b17268e57c944a79a00e8a56e26?s=96&d=mm&r=g","caption":"editor"},"url":"https:\/\/periodicorealidades.com\/index.php\/author\/editor\/"}]}},"_links":{"self":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/69802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/comments?post=69802"}],"version-history":[{"count":1,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/69802\/revisions"}],"predecessor-version":[{"id":69803,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/69802\/revisions\/69803"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/media\/69530"}],"wp:attachment":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/media?parent=69802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/categories?post=69802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/tags?post=69802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}