{"id":70305,"date":"2026-05-24T22:47:53","date_gmt":"2026-05-25T05:47:53","guid":{"rendered":"https:\/\/periodicorealidades.com\/?p=70305"},"modified":"2026-05-24T22:47:53","modified_gmt":"2026-05-25T05:47:53","slug":"fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua","status":"publish","type":"post","link":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/24\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\/","title":{"rendered":"FGR cita a declarar a gobernadora Maru Campos del estado de Chihuahua"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La gobernadora panista de Chihuahua, Mar\u00eda Eugenia Campos Galv\u00e1n, recibi\u00f3 este s\u00e1bado un citatorio por parte de la Fiscal\u00eda General de la Rep\u00fablica (FGR) para comparecer respecto a la colaboraci\u00f3n de su gobierno con agentes estadounidenses en operativos realizados en la entidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por: Agencias<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chihuahua, Chihuahua; lunes, 25 de mayo del 2026.- El requerimiento fue entregado al mediod\u00eda por dos agentes ministeriales de la FGR a las afueras del Palacio de Gobierno y recibido por el consejero jur\u00eddico estatal. La mandataria deber\u00e1 presentarse el pr\u00f3ximo mi\u00e9rcoles 27 de mayo a las 10:00 horas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras recibir el documento, Campos Galv\u00e1n confirm\u00f3 p\u00fablicamente que el citatorio estaba dirigido a ella y asegur\u00f3 que acudir\u00e1 a comparecer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAh\u00ed estaremos, porque siempre he dado la cara\u201d, declar\u00f3 la gobernadora, quien adem\u00e1s lament\u00f3 que, seg\u00fan dijo, se est\u00e9 afectando la institucionalidad en Chihuahua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, se\u00f1al\u00f3 que, pese a contar con fuero constitucional, tendr\u00e1 que acudir ante la autoridad federal. Tambi\u00e9n compar\u00f3 su caso con el de otros gobernadores del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un comunicado, la FGR explic\u00f3 que la comparecencia est\u00e1 relacionada con la presencia de agentes de la CIA en un operativo antinarc\u00f3ticos realizado en la Sierra del Pinal, Chihuahua, los d\u00edas 17 y 18 de abril.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La dependencia inform\u00f3 que tanto la gobernadora como el ex fiscal general del estado fueron citados en calidad de testigos para recabar entrevistas ministeriales y esclarecer los hechos investigados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s tarde, Mar\u00eda Eugenia Campos public\u00f3 un video en redes sociales donde afirm\u00f3 ser v\u00edctima de \u201cpersecuci\u00f3n pol\u00edtica\u201d y acus\u00f3 a las autoridades de \u201cproteger a los delincuentes y perseguir a quienes s\u00ed cumplimos con nuestro deber\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, reiter\u00f3 que continuar\u00e1 defendiendo a Chihuahua y asegur\u00f3 que seguir\u00e1 \u201cdando la cara\u201d por el estado y por M\u00e9xico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La gobernadora panista de Chihuahua, Mar\u00eda Eugenia Campos Galv\u00e1n, recibi\u00f3 este s\u00e1bado un citatorio por parte de la Fiscal\u00eda General de la Rep\u00fablica (FGR) para comparecer respecto a la colaboraci\u00f3n de su gobierno con agentes estadounidenses en operativos realizados en la entidad. Por: Agencias Chihuahua, Chihuahua; lunes, 25 de mayo del 2026.- El requerimiento fue [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":68747,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,4],"tags":[],"class_list":["post-70305","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacional","category-principal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FGR cita a declarar a gobernadora Maru Campos del estado de Chihuahua - Peri\u00f3dico Realidades<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/24\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FGR cita a declarar a gobernadora Maru Campos del estado de Chihuahua - Peri\u00f3dico Realidades\" \/>\n<meta property=\"og:description\" content=\"La gobernadora panista de Chihuahua, Mar\u00eda Eugenia Campos Galv\u00e1n, recibi\u00f3 este s\u00e1bado un citatorio por parte de la Fiscal\u00eda General de la Rep\u00fablica (FGR) para comparecer respecto a la colaboraci\u00f3n de su gobierno con agentes estadounidenses en operativos realizados en la entidad. Por: Agencias Chihuahua, Chihuahua; lunes, 25 de mayo del 2026.- El requerimiento fue [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/24\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\/\" \/>\n<meta property=\"og:site_name\" content=\"Peri\u00f3dico Realidades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-25T05:47:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/05\/Maru-Campos-@MaruCampos_G-1160x700-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/05\\\/24\\\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/05\\\/24\\\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\\\/\"},\"author\":{\"name\":\"editor\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/c27da34ee13acaec3162071a3e1c7832\"},\"headline\":\"FGR cita a declarar a gobernadora Maru Campos del estado de Chihuahua\",\"datePublished\":\"2026-05-25T05:47:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/05\\\/24\\\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\\\/\"},\"wordCount\":320,\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/05\\\/24\\\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Maru-Campos-@MaruCampos_G-1160x700-1.jpg\",\"articleSection\":[\"Nacional\",\"Principal\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/05\\\/24\\\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/05\\\/24\\\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\\\/\",\"name\":\"FGR cita a declarar a gobernadora Maru Campos del estado de Chihuahua - Peri\u00f3dico Realidades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/05\\\/24\\\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/05\\\/24\\\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Maru-Campos-@MaruCampos_G-1160x700-1.jpg\",\"datePublished\":\"2026-05-25T05:47:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/05\\\/24\\\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/05\\\/24\\\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/05\\\/24\\\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\\\/#primaryimage\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Maru-Campos-@MaruCampos_G-1160x700-1.jpg\",\"contentUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Maru-Campos-@MaruCampos_G-1160x700-1.jpg\",\"width\":1160,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/2026\\\/05\\\/24\\\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/periodicorealidades.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FGR cita a declarar a gobernadora Maru Campos del estado de Chihuahua\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#website\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"name\":\"Peri\u00f3dico Realidades\",\"description\":\"M\u00e9dio de comunicaci\u00f3n en Nayarit\",\"publisher\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/periodicorealidades.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#organization\",\"name\":\"Peri\u00f3dico Realidades\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"contentUrl\":\"https:\\\/\\\/periodicorealidades.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/r-prueba.png\",\"width\":709,\"height\":709,\"caption\":\"Peri\u00f3dico Realidades\"},\"image\":{\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/periodicorealidades.denayarit?mibextid=LQQJ4d\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/periodicorealidades.com\\\/#\\\/schema\\\/person\\\/c27da34ee13acaec3162071a3e1c7832\",\"name\":\"editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dda3c3f59ea25f4b53cd53df977b0b2628039b17268e57c944a79a00e8a56e26?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dda3c3f59ea25f4b53cd53df977b0b2628039b17268e57c944a79a00e8a56e26?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dda3c3f59ea25f4b53cd53df977b0b2628039b17268e57c944a79a00e8a56e26?s=96&d=mm&r=g\",\"caption\":\"editor\"},\"url\":\"https:\\\/\\\/periodicorealidades.com\\\/index.php\\\/author\\\/editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FGR cita a declarar a gobernadora Maru Campos del estado de Chihuahua - Peri\u00f3dico Realidades","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/24\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\/","og_locale":"es_MX","og_type":"article","og_title":"FGR cita a declarar a gobernadora Maru Campos del estado de Chihuahua - Peri\u00f3dico Realidades","og_description":"La gobernadora panista de Chihuahua, Mar\u00eda Eugenia Campos Galv\u00e1n, recibi\u00f3 este s\u00e1bado un citatorio por parte de la Fiscal\u00eda General de la Rep\u00fablica (FGR) para comparecer respecto a la colaboraci\u00f3n de su gobierno con agentes estadounidenses en operativos realizados en la entidad. Por: Agencias Chihuahua, Chihuahua; lunes, 25 de mayo del 2026.- El requerimiento fue [&hellip;]","og_url":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/24\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\/","og_site_name":"Peri\u00f3dico Realidades","article_publisher":"https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d","article_published_time":"2026-05-25T05:47:53+00:00","og_image":[{"width":1160,"height":700,"url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/05\/Maru-Campos-@MaruCampos_G-1160x700-1.jpg","type":"image\/jpeg"}],"author":"editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/24\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\/#article","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/24\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\/"},"author":{"name":"editor","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/c27da34ee13acaec3162071a3e1c7832"},"headline":"FGR cita a declarar a gobernadora Maru Campos del estado de Chihuahua","datePublished":"2026-05-25T05:47:53+00:00","mainEntityOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/24\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\/"},"wordCount":320,"publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/24\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\/#primaryimage"},"thumbnailUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/05\/Maru-Campos-@MaruCampos_G-1160x700-1.jpg","articleSection":["Nacional","Principal"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/24\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\/","url":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/24\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\/","name":"FGR cita a declarar a gobernadora Maru Campos del estado de Chihuahua - Peri\u00f3dico Realidades","isPartOf":{"@id":"https:\/\/periodicorealidades.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/24\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\/#primaryimage"},"image":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/24\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\/#primaryimage"},"thumbnailUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/05\/Maru-Campos-@MaruCampos_G-1160x700-1.jpg","datePublished":"2026-05-25T05:47:53+00:00","breadcrumb":{"@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/24\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/periodicorealidades.com\/index.php\/2026\/05\/24\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/24\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\/#primaryimage","url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/05\/Maru-Campos-@MaruCampos_G-1160x700-1.jpg","contentUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2026\/05\/Maru-Campos-@MaruCampos_G-1160x700-1.jpg","width":1160,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/periodicorealidades.com\/index.php\/2026\/05\/24\/fgr-cita-a-declarar-a-gobernadora-maru-campos-del-estado-de-chihuahua\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/periodicorealidades.com\/"},{"@type":"ListItem","position":2,"name":"FGR cita a declarar a gobernadora Maru Campos del estado de Chihuahua"}]},{"@type":"WebSite","@id":"https:\/\/periodicorealidades.com\/#website","url":"https:\/\/periodicorealidades.com\/","name":"Peri\u00f3dico Realidades","description":"M\u00e9dio de comunicaci\u00f3n en Nayarit","publisher":{"@id":"https:\/\/periodicorealidades.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/periodicorealidades.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/periodicorealidades.com\/#organization","name":"Peri\u00f3dico Realidades","url":"https:\/\/periodicorealidades.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/","url":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","contentUrl":"https:\/\/periodicorealidades.com\/wp-content\/uploads\/2023\/05\/r-prueba.png","width":709,"height":709,"caption":"Peri\u00f3dico Realidades"},"image":{"@id":"https:\/\/periodicorealidades.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/periodicorealidades.denayarit?mibextid=LQQJ4d"]},{"@type":"Person","@id":"https:\/\/periodicorealidades.com\/#\/schema\/person\/c27da34ee13acaec3162071a3e1c7832","name":"editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/dda3c3f59ea25f4b53cd53df977b0b2628039b17268e57c944a79a00e8a56e26?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dda3c3f59ea25f4b53cd53df977b0b2628039b17268e57c944a79a00e8a56e26?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dda3c3f59ea25f4b53cd53df977b0b2628039b17268e57c944a79a00e8a56e26?s=96&d=mm&r=g","caption":"editor"},"url":"https:\/\/periodicorealidades.com\/index.php\/author\/editor\/"}]}},"_links":{"self":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/70305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/comments?post=70305"}],"version-history":[{"count":1,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/70305\/revisions"}],"predecessor-version":[{"id":70306,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/posts\/70305\/revisions\/70306"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/media\/68747"}],"wp:attachment":[{"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/media?parent=70305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/categories?post=70305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/periodicorealidades.com\/index.php\/wp-json\/wp\/v2\/tags?post=70305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}